{"id":35955,"date":"2013-07-22T17:13:14","date_gmt":"2013-07-22T15:13:14","guid":{"rendered":"https:\/\/www.toutsurmesfinances.com\/placements\/pea-pme-conditions-fonctionnement-et-fiscalite-du-pea-dedie-aux-pme-eti.html"},"modified":"2021-07-23T20:26:54","modified_gmt":"2021-07-23T18:26:54","slug":"pea-pme-conditions-fonctionnement-et-fiscalite-du-pea-dedie-aux-pme-eti","status":"publish","type":"post","link":"https:\/\/www.toutsurmesfinances.com\/bourse\/a\/pea-pme-conditions-fonctionnement-et-fiscalite-du-pea-dedie-aux-pme-eti","title":{"rendered":"PEA-PME : conditions, fonctionnement et fiscalit\u00e9 du PEA d\u00e9di\u00e9 aux PME-ETI"},"content":{"rendered":"<h2><span class=\"ez-toc-section\" id=\"PEA-PME_definition\"><\/span>PEA-PME, d\u00e9finition<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h3>Le PEA-PME, c&rsquo;est quoi ?<\/h3>\n<p>Le PEA-PME est une enveloppe d\u2019investissement compl\u00e9mentaire au <a href=\"https:\/\/www.toutsurmesfinances.com\/bourse\/a\/le-pea\">plan d\u2019\u00e9pargne en actions (PEA)<\/a>. Ce compte peut \u00eatre ouvert ind\u00e9pendamment ou en compl\u00e9ment d\u2019un PEA classique.<\/p>\n<p>Il permet \u00e0 un actionnaire individuel d\u2019effectuer des investissements sp\u00e9cifiquement dans les petites et moyennes entreprises (PME) et les entreprises de taille interm\u00e9diaire (ETI) principalement cot\u00e9es en Bourse, mais aussi non cot\u00e9es, dans le cadre de la fiscalit\u00e9 avantageuse du PEA. Le PEA-PME est parfois appel\u00e9 PEA-PME-ETI.<\/p>\n<p>Cette enveloppe d\u00e9di\u00e9e aux PME-ETI est plafonn\u00e9e \u00e0 225.000 euros de versements par titulaire, sachant que le plafond cumul\u00e9 PEA + PEA-PME est \u00e9galement fix\u00e9 \u00e0 225.000 euros depuis le 24 mai 2019.<\/p>\n<p>Le PEA-PME a b\u00e9n\u00e9fici\u00e9 d\u2019assouplissements successifs depuis sa cr\u00e9ation par la loi de finances pour 2014 (LFI 2014) ; le dernier en date est intervenu dans le cadre de la loi Pacte du 22 mai 2019.<\/p>\n<h3>Le PEA-PME, pour quoi faire ?<\/h3>\n<p>Le PEA-PME sert principalement \u00e0 investir en Bourse, au capital de PME et d\u2019ETI fran\u00e7aises ou europ\u00e9ennes cot\u00e9es, afin de faire fructifier un capital en franchise d\u2019imp\u00f4t sur le revenu.<\/p>\n<p>Le PEA-PME est en effet un moyen de g\u00e9rer un portefeuille d\u2019actions sans \u00eatre soumis \u00e0 l\u2019imp\u00f4t sur le revenu ni aux pr\u00e9l\u00e8vements sociaux \u00e0 chaque plus-value\u00a0; la fiscalit\u00e9 est uniquement due en cas de sortie du PEA-PME.<\/p>\n<p>Le PEA-PME est donc une enveloppe de capitalisation, au m\u00eame titre que :<\/p>\n<ul>\n<li>le PEA classique<\/li>\n<li>le PEA jeunes<\/li>\n<li><a href=\"https:\/\/www.toutsurmesfinances.com\/placements\/assurance-vie-fonctionnement-et-explications.html\">l\u2019assurance vie<\/a><\/li>\n<li>le contrat de capitalisation<\/li>\n<li><a href=\"https:\/\/www.toutsurmesfinances.com\/retraite\/plan-epargne-retraite-per.html\">le plan d\u2019\u00e9pargne retraite (PER)<\/a><\/li>\n<li>les anciens contrats d\u2019\u00e9pargne retraite comme le Perp et le contrat Madelin<\/li>\n<\/ul>\n<p>Le PEA-PME vise, pour les pouvoirs publics, \u00e0 remplir de nombreux objectifs :<\/p>\n<ul>\n<li>r\u00e9orienter l\u2019\u00e9pargne des Fran\u00e7ais vers l\u2019\u00e9conomie r\u00e9elle, en particulier les PME et les ETI cot\u00e9es et non cot\u00e9es en Bourse<\/li>\n<li>relancer l\u2019attractivit\u00e9 de la classe d\u2019actifs \u00ab Actions Fran\u00e7aises \u00bb hors CAC 40 aupr\u00e8s des petits porteurs<\/li>\n<li>diversifier les sources de financement des PME et ETI<\/li>\n<li>renforcer le capital des PME fran\u00e7aises, sous-capitalis\u00e9es<\/li>\n<li>favoriser <a href=\"https:\/\/www.toutsurmesfinances.com\/bourse\/c\/ipo-intros\">les introductions en Bourse<\/a> de PME-ETI en France<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"PEA-PME_comment_ca_marche\"><\/span>PEA-PME, comment \u00e7a marche ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Le PEA-PME est un compte permettant principalement, tout en b\u00e9n\u00e9ficiant de la fiscalit\u00e9 du PEA, d&rsquo;acheter et de vendre\u00a0des actions de soci\u00e9t\u00e9s cot\u00e9es en Bourse de type PME et ETI ne d\u00e9passant par une certaine taille (par le chiffre d\u2019affaires, le total de bilan ou le nombre de salari\u00e9s). Soci\u00e9t\u00e9s \u00e9ligibles mises \u00e0 part, c\u2019est un moyen de g\u00e9rer un portefeuille boursier comme on le fait dans un PEA ou un <a href=\"https:\/\/www.toutsurmesfinances.com\/bourse\/a\/le-compte-titre\">compte-titres ordinaire<\/a>, en passant des ordres d\u2019achats ou de vente de titres.<\/p>\n<p>D\u2019autres titres peuvent \u00eatre log\u00e9s dans un PEA-PME, tels que des parts de Sicav et FCP \u00e9ligibles aux PEA-PME, des titres de soci\u00e9t\u00e9s non cot\u00e9es, des obligations convertibles ou remboursables en actions et des titres de dettes souscrites via des plateformes de financement participatif. Toutefois, tous les courtiers en ligne ne permettent pas forc\u00e9ment d\u2019investir sur tous les supports autoris\u00e9s par la r\u00e9glementation.<\/p>\n<p>Le r\u00e9gime fiscal est calqu\u00e9 sur celui du PEA :<\/p>\n<ul>\n<li>gestion du portefeuille en franchise d\u2019imp\u00f4t<\/li>\n<li>imp\u00f4t et\/ou pr\u00e9l\u00e8vements dus uniquement en cas de sortie du PEA-PME<\/li>\n<li>en cas de sortie avant 5 ans : taxation au pr\u00e9l\u00e8vement forfaitaire unique, soit 12,8%<\/li>\n<li>en cas de sortie apr\u00e8s 5 ans : pas d\u2019imp\u00f4t sur le revenu<\/li>\n<\/ul>\n<p>Quelle que soit la date de sortie du plan, les pr\u00e9l\u00e8vements sociaux sont dus, au taux de 17,2%.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"PEA-PME_pour_qui\"><\/span>PEA-PME, pour qui ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Qui a int\u00e9r\u00eat \u00e0 ouvrir ou d\u00e9tenir un PEA-PME\u00a0?<\/p>\n<p>On peut distinguer plusieurs profils pour qui d\u00e9tenir un PEA-PME a du sens :<\/p>\n<ul>\n<li>titulaires d\u2019un PEA classique au plafond ou proches de l\u2019\u00eatre (150.000 euros depuis l\u2019ouverture)<\/li>\n<li>investisseurs souhaitant investir uniquement sur les petites et moyennes valeurs fran\u00e7aises<\/li>\n<li>personnes souhaitant diversifier leur portefeuille sur les actions fran\u00e7aises de petites et moyennes capitalisation, en profitant du r\u00e9gime fiscal du PEA<\/li>\n<li>personnes souhaitant, par conviction, investir au capital d\u2019entreprises fran\u00e7aises<\/li>\n<li>personnes souhaitant b\u00e9n\u00e9ficier de la fiscalit\u00e9 du PEA pour leurs titres non cot\u00e9s<\/li>\n<\/ul>\n<p>En pratique, les personnes d\u00e9tenant d\u00e9j\u00e0 un PEA classique n\u2019ont pas d\u2019int\u00e9r\u00eat particulier \u00e0 d\u00e9tenir un PEA-PME si le total de leurs versements est \u00e9loign\u00e9 du plafond de 150.000 euros.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Plafond_du_PEA-PME_quel_montant_maximum\"><\/span>Plafond du PEA-PME : quel montant maximum ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Le plafond de versements sur un PEA-PME est fix\u00e9 \u00e0 225.000 euros depuis le 24 mai 2019.<\/p>\n<p>Ce plafond est commun \u00e0 celui du PEA classique, sachant que le montant maximum de versements sur ce dernier est fix\u00e9 \u00e0 150.000 euros. Autrement dit, le plafond du PEA-PME de 225.000 euros est \u00e9gal \u00e0 la somme des versements sur un PEA et un PEA-PME depuis leur ouverture.<\/p>\n<p>Les versements sur un PEA-PME sont donc d\u00e9pendants des sommes d\u00e9j\u00e0 vers\u00e9es par le titulaire du plan sur un PEA classique.<\/p>\n<p>Ainsi, une personne d\u00e9j\u00e0 titulaire d\u2019un PEA classique, souhaitant ouvrir un PEA-PME, peut y verser :<\/p>\n<ul>\n<li>75.000 euros s\u2019il a vers\u00e9 150.000 euros sur son PEA<\/li>\n<li>100.000 euros s\u2019il a vers\u00e9 125.000 euros sur son PEA<\/li>\n<li>125.000 euros s\u2019il a vers\u00e9 100.000 euros sur son PEA<\/li>\n<li>150.000 euros s\u2019il a vers\u00e9 75.000 euros sur son PEA<\/li>\n<li>175.000 euros s\u2019il a vers\u00e9 50.000 euros sur son PEA<\/li>\n<li>200.000 euros s\u2019il a vers\u00e9 25.000 euros sur son PEA<\/li>\n<\/ul>\n<p>Le plafond du PEA-PME est donc compris entre 75.000 et 225.000 euros selon le montant d\u2019apports cumul\u00e9s faits sur un PEA existant.<\/p>\n<p>\u00c0 l\u2019origine, le plafond de versements sur le PEA-PME \u00e9tait fix\u00e9 \u00e0 75.000 euros.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Fiscalite_du_PEA-PME_quel_impot_sur_le_revenu\"><\/span>Fiscalit\u00e9 du PEA-PME\u00a0: quel imp\u00f4t sur le revenu<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>La fiscalit\u00e9 du PEA-PME est la m\u00eame que celle du PEA classique\u00a0:<\/p>\n<ul>\n<li>le portefeuille de titres est g\u00e9r\u00e9 en franchise d\u2019imp\u00f4t : aucun imp\u00f4t n\u2019est d\u00fb \u00e0 chaque plus-value ; l\u2019imp\u00f4t n\u2019est \u00e0 payer qu\u2019en cas de sortie de capitaux du PEA-PME<\/li>\n<li>en cas de sortie avant 5 ans, un imp\u00f4t de 12,8% est d\u00fb sur les gains, par application du pr\u00e9l\u00e8vement forfaitaire unique (PFU)<\/li>\n<li>en cas de sortie au moins 5 ans apr\u00e8s l\u2019ouverture du PEA-PME, les gains sont exon\u00e9r\u00e9s d\u2019imp\u00f4t sur le revenu<\/li>\n<li>les pr\u00e9l\u00e8vements sociaux sont dus dans tous les cas, au taux de 17,2%<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Avantages_et_limites_du_PEA-PME\"><\/span>Avantages et limites du PEA-PME<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h3>PEA-PME : quels avantages ?<\/h3>\n<p>Le principal avantage du PEA-PME est fiscal\u00a0: il permet d\u2019investir dans des valeurs fran\u00e7aises, de petite et moyenne capitalisation boursi\u00e8re (smallcaps, midcaps), tout en b\u00e9n\u00e9ficiant de la fiscalit\u00e9 pr\u00e9f\u00e9rentielle du PEA. En effet, le portefeuille g\u00e9r\u00e9 au sein d\u2019un PEA-PME n\u2019est pas soumis \u00e0 l\u2019imp\u00f4t tant son titulaire n\u2019effectue aucun retrait. De plus, au bout de 5 ans de d\u00e9tention, les gains sur le PEA sont exon\u00e9r\u00e9s d\u2019imp\u00f4t. Ainsi, toute sortie de PEA au-del\u00e0 du cinqui\u00e8me anniversaire du plan ne d\u00e9clenche aucune imposition sur le revenu. Le titulaire du plan est uniquement passible des pr\u00e9l\u00e8vements sociaux.<\/p>\n<p>Le second avantage du PEA-PME porte sur la nature des titres qu\u2019il peut accueillir : contrairement au PEA classique, il est possible d\u2019y loger :<\/p>\n<ul>\n<li>des obligations convertibles en actions (OCA)<\/li>\n<li>des obligations remboursables en actions (ORA)<\/li>\n<li>des titres de dettes souscrits via des plateformes de financement participatif : titres participatifs, obligations \u00e0 taux fixe et minibons<\/li>\n<\/ul>\n<p>Attention, ce choix permis par la loi se heurte en pratique \u00e0 l\u2019impossibilit\u00e9 chez certains courtiers de bourse en ligne, de loger des titres de dettes de plateformes de financement participatif.<\/p>\n<h3>Inconv\u00e9nients du PEA-PME<\/h3>\n<p>Le PEA-PME n\u2019a pas que des avantages\u00a0: son principal inconv\u00e9nient porte sur le choix de titres de soci\u00e9t\u00e9s cot\u00e9es offerts\u00a0: il est beaucoup plus restreint que sur le PEA puisque dans les faits, la liste de titres \u00e9ligibles ne comporte que des valeurs cot\u00e9es sur Euronext Paris, \u00e0 quelques rares exceptions pr\u00e8s.<\/p>\n<p>Un PEA-PME ne permet donc pas d\u2019investir :<\/p>\n<ul>\n<li>dans des actions de soci\u00e9t\u00e9s am\u00e9ricaines ou chinoises ou de tout autre pays hors Europe<\/li>\n<li>dans des titres de grandes soci\u00e9t\u00e9s fran\u00e7aises ou europ\u00e9ennes (blue chips)<\/li>\n<li>dans des fonds ou ETF investis dans des soci\u00e9t\u00e9s internationales<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"PEA-PME_et_PEA_plafond_titres_eligibles_quelles_differences\"><\/span>PEA-PME et PEA : plafond, titres \u00e9ligibles, quelles diff\u00e9rences ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Les principales diff\u00e9rences entre PEA et PEA-PME portent :<\/p>\n<ul>\n<li>sur le montant maximum des versements depuis l\u2019ouverture<\/li>\n<li>sur la nature des titres \u00e9ligibles<\/li>\n<\/ul>\n<p>Les diff\u00e9rences entre PEA-PME et PEA classiques sont r\u00e9sum\u00e9es dans le tableau ci-dessous\u00a0:<\/p>\n<div id=\"tablepress-47-scroll-wrapper\" class=\"tablepress-scroll-wrapper\">\n\n<table id=\"tablepress-47\" class=\"tablepress tablepress-id-47 tablepress-responsive\">\n<thead>\n<tr class=\"row-1 odd\">\n\t<th class=\"column-1\">&nbsp;<\/th><th class=\"column-2\">PEA-PME<\/th><th class=\"column-3\">PEA<\/th>\n<\/tr>\n<\/thead>\n<tfoot>\n<tr class=\"row-15 odd\">\n\t<th colspan=\"3\" class=\"column-1\">Sources : Code mon\u00e9taire et financier, Code g\u00e9n\u00e9ral des imp\u00f4ts, Boursorama<\/th>\n<\/tr>\n<\/tfoot>\n<tbody class=\"row-hover\">\n<tr class=\"row-2 even\">\n\t<td class=\"column-1\">Fiscalit\u00e9<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td>\n<\/tr>\n<tr class=\"row-3 odd\">\n\t<td class=\"column-1\">Fiscalit\u00e9 avant 5 ans<\/td><td class=\"column-2\">PFU (12,8%)<\/td><td class=\"column-3\">PFU (12,8%)<\/td>\n<\/tr>\n<tr class=\"row-4 even\">\n\t<td class=\"column-1\">Fiscalit\u00e9 apr\u00e8s 5 ans<\/td><td class=\"column-2\">Exon\u00e9ration<\/td><td class=\"column-3\">Exon\u00e9ration<\/td>\n<\/tr>\n<tr class=\"row-5 odd\">\n\t<td class=\"column-1\">Pr\u00e9l\u00e8vements sociaux<\/td><td class=\"column-2\">0.172<\/td><td class=\"column-3\">0.172<\/td>\n<\/tr>\n<tr class=\"row-6 even\">\n\t<td class=\"column-1\">Titres \u00e9ligibles<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td>\n<\/tr>\n<tr class=\"row-7 odd\">\n\t<td class=\"column-1\">Si\u00e8ge social<\/td><td class=\"column-2\">France, UE, EEE<\/td><td class=\"column-3\">France, UE, EEE<\/td>\n<\/tr>\n<tr class=\"row-8 even\">\n\t<td class=\"column-1\">Soci\u00e9t\u00e9s du CAC 40<\/td><td class=\"column-2\">Non<\/td><td class=\"column-3\">Oui<\/td>\n<\/tr>\n<tr class=\"row-9 odd\">\n\t<td class=\"column-1\">Actions am\u00e9ricaines<\/td><td class=\"column-2\">Non<\/td><td class=\"column-3\">Non<\/td>\n<\/tr>\n<tr class=\"row-10 even\">\n\t<td class=\"column-1\">Trackers \u00e9ligibles<\/td><td class=\"column-2\">1 seul<\/td><td class=\"column-3\">&gt; 200 *<\/td>\n<\/tr>\n<tr class=\"row-11 odd\">\n\t<td class=\"column-1\">Pr\u00eats financement participatif<\/td><td class=\"column-2\">Oui<\/td><td class=\"column-3\">Non<\/td>\n<\/tr>\n<tr class=\"row-12 even\">\n\t<td class=\"column-1\">Obligations convertibles<\/td><td class=\"column-2\">Oui<\/td><td class=\"column-3\">Non<\/td>\n<\/tr>\n<tr class=\"row-13 odd\">\n\t<td class=\"column-1\">Condition d'effectif<\/td><td class=\"column-2\">Moins de 5.000 personnes<\/td><td class=\"column-3\">Aucune<\/td>\n<\/tr>\n<tr class=\"row-14 even\">\n\t<td class=\"column-1\">Condition de taille<\/td><td class=\"column-2\">CA &lt; \u00e0 1,5 milliard d&#039;\u20ac ou total de bilan \u2264 2 milliards d&#039;\u20ac <\/td><td class=\"column-3\">Aucune<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n<\/div><!-- #tablepress-47 from cache -->\n<h2><span class=\"ez-toc-section\" id=\"PEA-PME_liste_Euronext_des_actions_eligibles_en_2021\"><\/span>PEA-PME : liste Euronext des actions \u00e9ligibles en 2021<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Il n\u2019existe aucune liste officielle des titres \u00e9ligibles au PEA-PME \u00e9tablie par les services de l\u2019Etat. La seule source de r\u00e9f\u00e9rence est le listing r\u00e9guli\u00e8rement mis \u00e0 jour par Euronext, l\u2019op\u00e9rateur de la Bourse de Paris, bas\u00e9e sur les soci\u00e9t\u00e9s cot\u00e9es sur les march\u00e9s actions d\u2019Euronext ayant publiquement communiqu\u00e9 leur \u00e9ligibilit\u00e9 au PEA-PME et ayant notifi\u00e9 Euronext d\u2019une telle communication.<\/p>\n<div id=\"tablepress-46-scroll-wrapper\" class=\"tablepress-scroll-wrapper\">\n\n<table id=\"tablepress-46\" class=\"tablepress tablepress-id-46 tablepress-responsive\">\n<thead>\n<tr class=\"row-1 odd\">\n\t<th class=\"column-1\">Soci\u00e9t\u00e9<\/th><th class=\"column-2\">Code ISIN<\/th><th class=\"column-3\">March\u00e9<\/th><th class=\"column-4\">Compartiment<\/th><th class=\"column-5\">Si\u00e8ge social<\/th>\n<\/tr>\n<\/thead>\n<tfoot>\n<tr class=\"row-378 even\">\n\t<th colspan=\"5\" class=\"column-1\">Source : Euronext (au 15\/07\/2021), retraitements ToutSurMesFinances.com<\/th>\n<\/tr>\n<\/tfoot>\n<tbody class=\"row-hover\">\n<tr class=\"row-2 even\">\n\t<td class=\"column-1\">1000MERCIS<\/td><td class=\"column-2\">FR0010285965<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-3 odd\">\n\t<td class=\"column-1\">2CRSI <\/td><td class=\"column-2\">FR0013341781<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-4 even\">\n\t<td class=\"column-1\">2MX ORGANIC SA<\/td><td class=\"column-2\">FR0014000T90<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-5 odd\">\n\t<td class=\"column-1\">AB SCIENCE<\/td><td class=\"column-2\">FR0010557264<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-6 even\">\n\t<td class=\"column-1\">ABC ARBITRAGE<\/td><td class=\"column-2\">FR0004040608<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-7 odd\">\n\t<td class=\"column-1\">ABEO SA<\/td><td class=\"column-2\">FR0013185857<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-8 even\">\n\t<td class=\"column-1\">ABIONYX PHARMA<\/td><td class=\"column-2\">FR0012616852<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-9 odd\">\n\t<td class=\"column-1\">ABIVAX<\/td><td class=\"column-2\">FR0012333284<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-10 even\">\n\t<td class=\"column-1\">ACTEOS<\/td><td class=\"column-2\">FR0000076861<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-11 odd\">\n\t<td class=\"column-1\">ACTIA GROUP<\/td><td class=\"column-2\">FR0000076655<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-12 even\">\n\t<td class=\"column-1\">ADEUNIS<\/td><td class=\"column-2\">FR0013284627<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-13 odd\">\n\t<td class=\"column-1\">ADL PARTNER<\/td><td class=\"column-2\">FR0000062978<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-14 even\">\n\t<td class=\"column-1\">ADOCIA<\/td><td class=\"column-2\">FR0011184241<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-15 odd\">\n\t<td class=\"column-1\">ADOMOS<\/td><td class=\"column-2\">FR0013247244<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-16 even\">\n\t<td class=\"column-1\">ADTHINK<\/td><td class=\"column-2\">FR0010457531<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-17 odd\">\n\t<td class=\"column-1\">ADUX<\/td><td class=\"column-2\">FR0012821890<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-18 even\">\n\t<td class=\"column-1\">ADVENIS <\/td><td class=\"column-2\">FR0004152874<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-19 odd\">\n\t<td class=\"column-1\">ADVICENNE<\/td><td class=\"column-2\">FR0013296746<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-20 even\">\n\t<td class=\"column-1\">ADVINI<\/td><td class=\"column-2\">FR0000053043<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-21 odd\">\n\t<td class=\"column-1\">AFFLUENT MEDICAL<\/td><td class=\"column-2\">FR0013333077<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-22 even\">\n\t<td class=\"column-1\">AG3i<\/td><td class=\"column-2\">FR0011908045<\/td><td class=\"column-3\">Euronext Access<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-23 odd\">\n\t<td class=\"column-1\">AGRIPOWER<\/td><td class=\"column-2\">FR0013452281<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-24 even\">\n\t<td class=\"column-1\">AIR MARINE<\/td><td class=\"column-2\">FR0013285103<\/td><td class=\"column-3\">Euronext Access<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-25 odd\">\n\t<td class=\"column-1\">ALBIOMA<\/td><td class=\"column-2\">FR0000060402<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-26 even\">\n\t<td class=\"column-1\">ALCHIMIE<\/td><td class=\"column-2\">FR0014000JX7<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-27 odd\">\n\t<td class=\"column-1\">ALEPH FINANCE<\/td><td class=\"column-2\">GB00BJ9M4V82<\/td><td class=\"column-3\">Euronext Access<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-28 even\">\n\t<td class=\"column-1\">ALES GROUPE<\/td><td class=\"column-2\">FR0000054652<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-29 odd\">\n\t<td class=\"column-1\">ALPHA M.O.S<\/td><td class=\"column-2\">FR0013421286<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-30 even\">\n\t<td class=\"column-1\">ALTHEORA<\/td><td class=\"column-2\">FR0000061244<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-31 odd\">\n\t<td class=\"column-1\">ALTUR Investissement<\/td><td class=\"column-2\">FR0010395681<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-32 even\">\n\t<td class=\"column-1\">AMOEBA<\/td><td class=\"column-2\">FR0011051598<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-33 odd\">\n\t<td class=\"column-1\">AMPLITUDE SURGICAL<\/td><td class=\"column-2\">FR0012789667<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-34 even\">\n\t<td class=\"column-1\">ANEVIA<\/td><td class=\"column-2\">FR0011910652<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-35 odd\">\n\t<td class=\"column-1\">ANTEVENIO<\/td><td class=\"column-2\">ES0109429037<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">Espagne<\/td>\n<\/tr>\n<tr class=\"row-36 even\">\n\t<td class=\"column-1\">AQUILA<\/td><td class=\"column-2\">FR0010340711<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-37 odd\">\n\t<td class=\"column-1\">ARCHOS<\/td><td class=\"column-2\">FR0000182479<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-38 even\">\n\t<td class=\"column-1\">ARCURE<\/td><td class=\"column-2\">FR0013398997<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-39 odd\">\n\t<td class=\"column-1\">ARTEFACT<\/td><td class=\"column-2\">FR0000079683<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-40 even\">\n\t<td class=\"column-1\">ARTMARKET.Com<\/td><td class=\"column-2\">FR0000074783<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-41 odd\">\n\t<td class=\"column-1\">ASHLER &amp; MANSON<\/td><td class=\"column-2\">FR0012968485<\/td><td class=\"column-3\">Euronext Access<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-42 even\">\n\t<td class=\"column-1\">AST GROUPE<\/td><td class=\"column-2\">FR0000076887<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-43 odd\">\n\t<td class=\"column-1\">ATARI<\/td><td class=\"column-2\">FR0010478248<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-44 even\">\n\t<td class=\"column-1\">ATEME<\/td><td class=\"column-2\">FR0011992700<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-45 odd\">\n\t<td class=\"column-1\">ATENOR<\/td><td class=\"column-2\">BE0003837540<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">Belgique<\/td>\n<\/tr>\n<tr class=\"row-46 even\">\n\t<td class=\"column-1\">AUDIOVALLEY<\/td><td class=\"column-2\">BE0974334667<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">Belgique<\/td>\n<\/tr>\n<tr class=\"row-47 odd\">\n\t<td class=\"column-1\">AUPLATA MINING GR<\/td><td class=\"column-2\">FR0013410370<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-48 even\">\n\t<td class=\"column-1\">AUREA<\/td><td class=\"column-2\">FR0000039232<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-49 odd\">\n\t<td class=\"column-1\">AURES TECHNOLOGIES<\/td><td class=\"column-2\">FR0013183589<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-50 even\">\n\t<td class=\"column-1\">AVENIR TELECOM<\/td><td class=\"column-2\">FR0000066052<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-51 odd\">\n\t<td class=\"column-1\">BAIKOWSKI<\/td><td class=\"column-2\">FR0013384369<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-52 even\">\n\t<td class=\"column-1\">BALYO<\/td><td class=\"column-2\">FR0013258399<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-53 odd\">\n\t<td class=\"column-1\">BARBARA BUI<\/td><td class=\"column-2\">FR0000062788<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-54 even\">\n\t<td class=\"column-1\">BARCO<\/td><td class=\"column-2\">BE0003790079<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">A<\/td><td class=\"column-5\">Belgique<\/td>\n<\/tr>\n<tr class=\"row-55 odd\">\n\t<td class=\"column-1\">BASSAC<\/td><td class=\"column-2\">FR0004023208<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-56 even\">\n\t<td class=\"column-1\">BASTIDE LE CONFORT<\/td><td class=\"column-2\">FR0000035370<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-57 odd\">\n\t<td class=\"column-1\">BD MULTI MEDIA<\/td><td class=\"column-2\">FR0000035305<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-58 even\">\n\t<td class=\"column-1\">BE Semiconductor<\/td><td class=\"column-2\">NL0012866412<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">A<\/td><td class=\"column-5\">Pays-Bas<\/td>\n<\/tr>\n<tr class=\"row-59 odd\">\n\t<td class=\"column-1\">BIGBEN INTERACTIVE<\/td><td class=\"column-2\">FR0000074072<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-60 even\">\n\t<td class=\"column-1\">BILENDI<\/td><td class=\"column-2\">FR0004174233<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-61 odd\">\n\t<td class=\"column-1\">BIOCORP<\/td><td class=\"column-2\">FR0012788065<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-62 even\">\n\t<td class=\"column-1\">BIOPHYTIS<\/td><td class=\"column-2\">FR0012816825<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-63 odd\">\n\t<td class=\"column-1\">BIOSYNEX<\/td><td class=\"column-2\">FR0011005933<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-64 even\">\n\t<td class=\"column-1\">BIOTALYS<\/td><td class=\"column-2\">BE0974386188<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">Belgique<\/td>\n<\/tr>\n<tr class=\"row-65 odd\">\n\t<td class=\"column-1\">BIO-UV GROUP<\/td><td class=\"column-2\">FR0013345493<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-66 even\">\n\t<td class=\"column-1\">BLUE SHARK POWER<\/td><td class=\"column-2\">FR0013340973<\/td><td class=\"column-3\">Euronext Access<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-67 odd\">\n\t<td class=\"column-1\">BLUELINEA<\/td><td class=\"column-2\">FR0011041011<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-68 even\">\n\t<td class=\"column-1\">BOA CONCEPT<\/td><td class=\"column-2\">FR0011365907<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-69 odd\">\n\t<td class=\"column-1\">BODY ONE<\/td><td class=\"column-2\">FR0010106039<\/td><td class=\"column-3\">Euronext Access<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-70 even\">\n\t<td class=\"column-1\">BONE THERAPEUTICS<\/td><td class=\"column-2\">BE0974280126<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">Belgique<\/td>\n<\/tr>\n<tr class=\"row-71 odd\">\n\t<td class=\"column-1\">BOOSTHEAT<\/td><td class=\"column-2\">FR0011814938<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-72 even\">\n\t<td class=\"column-1\">BOURSE DIRECT<\/td><td class=\"column-2\">FR0000074254<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-73 odd\">\n\t<td class=\"column-1\">CABASSE GROUP<\/td><td class=\"column-2\">FR0011800218<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-74 even\">\n\t<td class=\"column-1\">CAFOM<\/td><td class=\"column-2\">FR0010151589<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-75 odd\">\n\t<td class=\"column-1\">CANDELA INVEST<\/td><td class=\"column-2\">BE0974298300<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">Belgique<\/td>\n<\/tr>\n<tr class=\"row-76 even\">\n\t<td class=\"column-1\">CAPELLI<\/td><td class=\"column-2\">FR0012969095<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-77 odd\">\n\t<td class=\"column-1\">CARBIOS<\/td><td class=\"column-2\">FR0011648716<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-78 even\">\n\t<td class=\"column-1\">CARMAT<\/td><td class=\"column-2\">FR0010907956<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-79 odd\">\n\t<td class=\"column-1\">CAST<\/td><td class=\"column-2\">FR0000072894<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-80 even\">\n\t<td class=\"column-1\">CBO TERRITORIA<\/td><td class=\"column-2\">FR0010193979<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-81 odd\">\n\t<td class=\"column-1\">CECURITY.COM<\/td><td class=\"column-2\">FR0010717579<\/td><td class=\"column-3\">Euronext Access<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-82 even\">\n\t<td class=\"column-1\">CELLECTIS<\/td><td class=\"column-2\">FR0010425595<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-83 odd\">\n\t<td class=\"column-1\">CELYAD ONCOLOGY<\/td><td class=\"column-2\">BE0974260896<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">Belgique<\/td>\n<\/tr>\n<tr class=\"row-84 even\">\n\t<td class=\"column-1\">CERINNOV GROUP<\/td><td class=\"column-2\">FR0013178712<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-85 odd\">\n\t<td class=\"column-1\">CHARGEURS<\/td><td class=\"column-2\">FR0000130692<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-86 even\">\n\t<td class=\"column-1\">CHAUSSERIA<\/td><td class=\"column-2\">FR0000060907<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-87 odd\">\n\t<td class=\"column-1\">CIBOX<\/td><td class=\"column-2\">FR0000054322<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-88 even\">\n\t<td class=\"column-1\">CIOA<\/td><td class=\"column-2\">FR0012384907<\/td><td class=\"column-3\">Euronext Access<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-89 odd\">\n\t<td class=\"column-1\">CLARANOVA<\/td><td class=\"column-2\">FR0013426004<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-90 even\">\n\t<td class=\"column-1\">CLASQUIN<\/td><td class=\"column-2\">FR0004152882<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-91 odd\">\n\t<td class=\"column-1\">CLIOBLUE<\/td><td class=\"column-2\">FR0011092089<\/td><td class=\"column-3\">Euronext Access<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-92 even\">\n\t<td class=\"column-1\">COFIDUR<\/td><td class=\"column-2\">FR0013257409<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-93 odd\">\n\t<td class=\"column-1\">COGELEC<\/td><td class=\"column-2\">FR0013335742<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-94 even\">\n\t<td class=\"column-1\">COGRA<\/td><td class=\"column-2\">FR0011071570<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-95 odd\">\n\t<td class=\"column-1\">COMPAGNIE DU MONT BLANC<\/td><td class=\"column-2\">FR0000060428<\/td><td class=\"column-3\">Euronext Access<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-96 even\">\n\t<td class=\"column-1\">COMPAGNIE INDUSTRIELLE ET FINANCIERE D\u2019ENTREPRISES CIFE<\/td><td class=\"column-2\">FR0000066219<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-97 odd\">\n\t<td class=\"column-1\">COMPAGNIE LEBON<\/td><td class=\"column-2\">FR0000121295<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-98 even\">\n\t<td class=\"column-1\">COURTOIS<\/td><td class=\"column-2\">FR0000065393<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-99 odd\">\n\t<td class=\"column-1\">CROSSJECT<\/td><td class=\"column-2\">FR0011716265<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-100 even\">\n\t<td class=\"column-1\">CROSSWOOD<\/td><td class=\"column-2\">FR0000050395<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-101 odd\">\n\t<td class=\"column-1\">CS GROUP<\/td><td class=\"column-2\">FR0007317813<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-102 even\">\n\t<td class=\"column-1\">CYBERGUN<\/td><td class=\"column-2\">FR0013204351<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-103 odd\">\n\t<td class=\"column-1\">DALET<\/td><td class=\"column-2\">FR0011026749<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">c<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-104 even\">\n\t<td class=\"column-1\">DAMARTEX<\/td><td class=\"column-2\">22\/07\/1900<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-105 odd\">\n\t<td class=\"column-1\">DATBIM<\/td><td class=\"column-2\">FR0004177939<\/td><td class=\"column-3\">Euronext Access<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-106 even\">\n\t<td class=\"column-1\">DBT (GROUPE)<\/td><td class=\"column-2\">26\/07\/1900<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-107 odd\">\n\t<td class=\"column-1\">DBV TECHNOLOGIES<\/td><td class=\"column-2\">FR0010417345<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-108 even\">\n\t<td class=\"column-1\">DEINOVE<\/td><td class=\"column-2\">FR0010879056<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-109 odd\">\n\t<td class=\"column-1\">DELFINGEN<\/td><td class=\"column-2\">FR0000054132<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-110 even\">\n\t<td class=\"column-1\">DELTA PLUS GROUP<\/td><td class=\"column-2\">FR0013283108<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-111 odd\">\n\t<td class=\"column-1\">DEVOTEAM<\/td><td class=\"column-2\">FR0000073793<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-112 even\">\n\t<td class=\"column-1\">DIAGNOSTIC MEDICAL<\/td><td class=\"column-2\">FR0012202497<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-113 odd\">\n\t<td class=\"column-1\">DLSI GROUPE<\/td><td class=\"column-2\">FR0010404368<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-114 even\">\n\t<td class=\"column-1\">DOLFINES<\/td><td class=\"column-2\">FR0010377127<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-115 odd\">\n\t<td class=\"column-1\">DONTNOD Entertainment SA<\/td><td class=\"column-2\">FR0013331212\u00a0<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-116 even\">\n\t<td class=\"column-1\">DRONE VOLT<\/td><td class=\"column-2\">FR0013088606<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-117 odd\">\n\t<td class=\"column-1\">E PANGO<\/td><td class=\"column-2\">FR0014004339<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-118 even\">\n\t<td class=\"column-1\">ECOSLOPS<\/td><td class=\"column-2\">FR0011490648<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-119 odd\">\n\t<td class=\"column-1\">EGIDE<\/td><td class=\"column-2\">FR0000072373<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-120 even\">\n\t<td class=\"column-1\">EKINOPS<\/td><td class=\"column-2\">FR0011466069<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-121 odd\">\n\t<td class=\"column-1\">EMOVA GROUP<\/td><td class=\"column-2\">FR0013356755 <\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-122 even\">\n\t<td class=\"column-1\">ENENSYS<\/td><td class=\"column-2\">FR0013330792<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-123 odd\">\n\t<td class=\"column-1\">ENERGISME<\/td><td class=\"column-2\">FR0013399359<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-124 even\">\n\t<td class=\"column-1\">ENERTIME<\/td><td class=\"column-2\">FR0011915339<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-125 odd\">\n\t<td class=\"column-1\">ENOGIA <\/td><td class=\"column-2\">FR0014004974<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-126 even\">\n\t<td class=\"column-1\">ENTREPARTICULIERS.COM<\/td><td class=\"column-2\">FR0010424697<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-127 odd\">\n\t<td class=\"column-1\">ENVEA<\/td><td class=\"column-2\">FR0010278762<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-128 even\">\n\t<td class=\"column-1\">EO2 <\/td><td class=\"column-2\">FR0010465534<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-129 odd\">\n\t<td class=\"column-1\">EOS IMAGING<\/td><td class=\"column-2\">FR0011191766<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-130 even\">\n\t<td class=\"column-1\">ERYTECH PHARMA<\/td><td class=\"column-2\">FR0011471135<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-131 odd\">\n\t<td class=\"column-1\">ESI GROUP<\/td><td class=\"column-2\">FR0004110310<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-132 even\">\n\t<td class=\"column-1\">ESKER<\/td><td class=\"column-2\">FR0000035818<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-133 odd\">\n\t<td class=\"column-1\">EUROBIO-SCIENTIFIC<\/td><td class=\"column-2\">FR0013240934<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-134 even\">\n\t<td class=\"column-1\">EUROMEDIS GROUPE<\/td><td class=\"column-2\">FR0000075343<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-135 odd\">\n\t<td class=\"column-1\">EUROPLASMA<\/td><td class=\"column-2\">FR0013514114<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-136 even\">\n\t<td class=\"column-1\">EUTELSAT<\/td><td class=\"column-2\">FR0010221234<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">A<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-137 odd\">\n\t<td class=\"column-1\">EVERGREEN (ex-DIGIGRAM)<\/td><td class=\"column-2\">FR0000035784<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-138 even\">\n\t<td class=\"column-1\">EVOLIS<\/td><td class=\"column-2\">FR0004166197<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-139 odd\">\n\t<td class=\"column-1\">EVS BROADCAST EQUIPMENT<\/td><td class=\"column-2\">BE0003820371<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">Belgique<\/td>\n<\/tr>\n<tr class=\"row-140 even\">\n\t<td class=\"column-1\">EXACOMPTA CLAIREFONTAINE<\/td><td class=\"column-2\">FR0000064164 <\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-141 odd\">\n\t<td class=\"column-1\">EXEL INDUSTRIES<\/td><td class=\"column-2\">FR0004527638<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-142 even\">\n\t<td class=\"column-1\">EXPLOSIFS ET PRODUITS CHIMIQUES (EPC)<\/td><td class=\"column-2\">FR0000039026<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-143 odd\">\n\t<td class=\"column-1\">FERMENTALG<\/td><td class=\"column-2\">FR0011271600<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-144 even\">\n\t<td class=\"column-1\">FIGEAC AERO<\/td><td class=\"column-2\">FR0011665280<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-145 odd\">\n\t<td class=\"column-1\">FILAE<\/td><td class=\"column-2\">FR0010221069<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-146 even\">\n\t<td class=\"column-1\">FLEURY MICHON<\/td><td class=\"column-2\">FR0000074759<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-147 odd\">\n\t<td class=\"column-1\">FOCUS HOME INTERACTIVE<\/td><td class=\"column-2\">FR0012419307<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-148 even\">\n\t<td class=\"column-1\">FONCIERE VOLTA<\/td><td class=\"column-2\">FR0000053944<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-149 odd\">\n\t<td class=\"column-1\">FOUNTAINE PAJOT<\/td><td class=\"column-2\">FR0010485268<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-150 even\">\n\t<td class=\"column-1\">FRANCAISE DE L ENERGIE<\/td><td class=\"column-2\">FR0013030152<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-151 odd\">\n\t<td class=\"column-1\">FRANCK DEVILLE<\/td><td class=\"column-2\">FR0012300424<\/td><td class=\"column-3\">Euronext Access<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-152 even\">\n\t<td class=\"column-1\">FREELANCE<\/td><td class=\"column-2\">FR0004187367<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-153 odd\">\n\t<td class=\"column-1\">GAUMONT<\/td><td class=\"column-2\">FR0000034894<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-154 even\">\n\t<td class=\"column-1\">GECI INTL<\/td><td class=\"column-2\">FR0000079634<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-155 odd\">\n\t<td class=\"column-1\">GENERIX<\/td><td class=\"column-2\">FR0010501692<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-156 even\">\n\t<td class=\"column-1\">GENFIT<\/td><td class=\"column-2\">FR0004163111<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-157 odd\">\n\t<td class=\"column-1\">GENKYOTEX<\/td><td class=\"column-2\">FR0013399474<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-158 even\">\n\t<td class=\"column-1\">GENOMIC VISION<\/td><td class=\"column-2\">FR0011799907<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-159 odd\">\n\t<td class=\"column-1\">GENOWAY<\/td><td class=\"column-2\">FR0004053510<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-160 even\">\n\t<td class=\"column-1\">GenSight Biologics<\/td><td class=\"column-2\">FR0013183985<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-161 odd\">\n\t<td class=\"column-1\">GERARD PERRIER<\/td><td class=\"column-2\">FR0000061459<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-162 even\">\n\t<td class=\"column-1\">GET LINK SE<\/td><td class=\"column-2\">FR0010533075<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">A<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-163 odd\">\n\t<td class=\"column-1\">GL EVENTS<\/td><td class=\"column-2\">FR0000066672<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-164 even\">\n\t<td class=\"column-1\">GLOBAL BIOENERGIES<\/td><td class=\"column-2\">FR0011052257<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-165 odd\">\n\t<td class=\"column-1\">GLOBAL ECOPOWER<\/td><td class=\"column-2\">FR0011289198<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-166 even\">\n\t<td class=\"column-1\">GOUR MEDICAL<\/td><td class=\"column-2\">FR0013371507<\/td><td class=\"column-3\">Euronext Access<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-167 odd\">\n\t<td class=\"column-1\">GRAINES VOLTZ<\/td><td class=\"column-2\">FR0000065971<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-168 even\">\n\t<td class=\"column-1\">GREENVOLT<\/td><td class=\"column-2\">PTGNV0AM0001<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">Portugal<\/td>\n<\/tr>\n<tr class=\"row-169 odd\">\n\t<td class=\"column-1\">GROUPE ARTEA<\/td><td class=\"column-2\">FR0012185536<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-170 even\">\n\t<td class=\"column-1\">GROUPE CASOL<\/td><td class=\"column-2\">FR0014003RM7<\/td><td class=\"column-3\">Euronext Access<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-171 odd\">\n\t<td class=\"column-1\">GROUPE GORGE<\/td><td class=\"column-2\">FR0000062671<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-172 even\">\n\t<td class=\"column-1\">GROUPE GUILLIN<\/td><td class=\"column-2\">FR0012819381<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-173 odd\">\n\t<td class=\"column-1\">GROUPE OPEN<\/td><td class=\"column-2\">FR0004050300<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-174 even\">\n\t<td class=\"column-1\">GROUPE PAROT<\/td><td class=\"column-2\">FR0013204070<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-175 odd\">\n\t<td class=\"column-1\">GROUPE PARTOUCHE<\/td><td class=\"column-2\">FR0012612646<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-176 even\">\n\t<td class=\"column-1\">GROUPE SFPI<\/td><td class=\"column-2\">FR0004155000<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-177 odd\">\n\t<td class=\"column-1\">GROUPE TERA<\/td><td class=\"column-2\">FR0013429404<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-178 even\">\n\t<td class=\"column-1\">GUERBET<\/td><td class=\"column-2\">FR0000032526<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-179 odd\">\n\t<td class=\"column-1\">HAULOTTE GROUP<\/td><td class=\"column-2\">FR0000066755<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-180 even\">\n\t<td class=\"column-1\">HDF <\/td><td class=\"column-2\">FR0014003VY4<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-181 odd\">\n\t<td class=\"column-1\">HERIGE<\/td><td class=\"column-2\">FR0000066540<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-182 even\">\n\t<td class=\"column-1\">HEXAOM<\/td><td class=\"column-2\">FR0004159473<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-183 odd\">\n\t<td class=\"column-1\">HF COMPANY<\/td><td class=\"column-2\">FR0000038531<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-184 even\">\n\t<td class=\"column-1\">HIGH CO<\/td><td class=\"column-2\">FR0000054231<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-185 odd\">\n\t<td class=\"column-1\">HIPAY<\/td><td class=\"column-2\">FR0012821916<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-186 even\">\n\t<td class=\"column-1\">HOFFMANN GREEN CEMENT TECHNOLOGIES<\/td><td class=\"column-2\">FR0013451044<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-187 odd\">\n\t<td class=\"column-1\">HOPIUM<\/td><td class=\"column-2\">FR0014000U63<\/td><td class=\"column-3\">Euronext Access<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-188 even\">\n\t<td class=\"column-1\">HOPSCOTCH GROUPE<\/td><td class=\"column-2\">FR0000065278<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-189 odd\">\n\t<td class=\"column-1\">HYBRIGENICS<\/td><td class=\"column-2\">FR0004153930<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-190 even\">\n\t<td class=\"column-1\">HYDROGEN REFUELING SA<\/td><td class=\"column-2\">FR0014001PM5<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-191 odd\">\n\t<td class=\"column-1\">ICERAM<\/td><td class=\"column-2\">FR0011511971<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-192 even\">\n\t<td class=\"column-1\">IDI<\/td><td class=\"column-2\">FR0000051393<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-193 odd\">\n\t<td class=\"column-1\">IKONISYS<\/td><td class=\"column-2\">FR00140048X2<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-194 even\">\n\t<td class=\"column-1\">IMMERSION<\/td><td class=\"column-2\">FR0013060100<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-195 odd\">\n\t<td class=\"column-1\">IMPLANET<\/td><td class=\"column-2\">FR0013470168<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-196 even\">\n\t<td class=\"column-1\">IMPULSE FITNESS<\/td><td class=\"column-2\">ES0105590006<\/td><td class=\"column-3\">Euronext Access<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">Espagne<\/td>\n<\/tr>\n<tr class=\"row-197 odd\">\n\t<td class=\"column-1\">INFOTEL<\/td><td class=\"column-2\">FR0000071797<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-198 even\">\n\t<td class=\"column-1\">INNATE PHARMA<\/td><td class=\"column-2\">FR0010331421<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-199 odd\">\n\t<td class=\"column-1\">INTEGRAGEN<\/td><td class=\"column-2\">FR0010908723<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-200 even\">\n\t<td class=\"column-1\">INTEGRITAS VIAGER<\/td><td class=\"column-2\">FR0014003FN0<\/td><td class=\"column-3\">Euronext Access<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-201 odd\">\n\t<td class=\"column-1\">INTRASENSE<\/td><td class=\"column-2\">FR0011179886<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-202 even\">\n\t<td class=\"column-1\">INVENTIVA<\/td><td class=\"column-2\">FR0013233012<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-203 odd\">\n\t<td class=\"column-1\">INVIBES<\/td><td class=\"column-2\">BE0974299316<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-204 even\">\n\t<td class=\"column-1\">IT LINK<\/td><td class=\"column-2\">FR0000072597<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-205 odd\">\n\t<td class=\"column-1\">ITESOFT<\/td><td class=\"column-2\">FR0004026151<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-206 even\">\n\t<td class=\"column-1\">JACQUES BOGART<\/td><td class=\"column-2\">FR0012872141<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-207 odd\">\n\t<td class=\"column-1\">JACQUET METALS<\/td><td class=\"column-2\">FR0000033904<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-208 even\">\n\t<td class=\"column-1\">KALRAY<\/td><td class=\"column-2\">FR0010722819<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-209 odd\">\n\t<td class=\"column-1\">KARLSEN<\/td><td class=\"column-2\">FR0011038348<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-210 even\">\n\t<td class=\"column-1\">KAUFMAN ET BROAD<\/td><td class=\"column-2\">FR0004007813 <\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-211 odd\">\n\t<td class=\"column-1\">KERLINK<\/td><td class=\"column-2\">FR0013156007<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-212 even\">\n\t<td class=\"column-1\">KEYRUS<\/td><td class=\"column-2\">FR0004029411<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-213 odd\">\n\t<td class=\"column-1\">KKO INTERNATIONAL<\/td><td class=\"column-2\">FR0013374667<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">Belgique<\/td>\n<\/tr>\n<tr class=\"row-214 even\">\n\t<td class=\"column-1\">KOMPUESTOS<\/td><td class=\"column-2\">ES0105425005<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">Espagne<\/td>\n<\/tr>\n<tr class=\"row-215 odd\">\n\t<td class=\"column-1\">KUMULUS VAPE<\/td><td class=\"column-2\">FR0013419876<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-216 even\">\n\t<td class=\"column-1\">LA FONCIERE VERTE<\/td><td class=\"column-2\">FR0000039638<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-217 odd\">\n\t<td class=\"column-1\">LACROIX<\/td><td class=\"column-2\">FR0000066607<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-218 even\">\n\t<td class=\"column-1\">LANSON-BCC<\/td><td class=\"column-2\">FR0004027068<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-219 odd\">\n\t<td class=\"column-1\">LARGO<\/td><td class=\"column-2\">FR0013308582<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-220 even\">\n\t<td class=\"column-1\">LATECOERE<\/td><td class=\"column-2\">FR0000032278<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-221 odd\">\n\t<td class=\"column-1\">LAURENT-PERRIER<\/td><td class=\"column-2\">FR0006864484<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-222 even\">\n\t<td class=\"column-1\">LDLC.COM<\/td><td class=\"column-2\">FR0000075442<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-223 odd\">\n\t<td class=\"column-1\">LE TANNEUR &amp; CIE<\/td><td class=\"column-2\">FR0000075673<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-224 even\">\n\t<td class=\"column-1\">LECTRA<\/td><td class=\"column-2\">FR0000065484<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-225 odd\">\n\t<td class=\"column-1\">LES AGENCES DE PAPA<\/td><td class=\"column-2\">FR0014003I41<\/td><td class=\"column-3\">Euronext Access<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-226 even\">\n\t<td class=\"column-1\">LES HOTELS BAVEREZ<\/td><td class=\"column-2\">FR0007080254<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-227 odd\">\n\t<td class=\"column-1\">LINEDATA SERVICES<\/td><td class=\"column-2\">FR0004156297<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-228 even\">\n\t<td class=\"column-1\">LLEIDA<\/td><td class=\"column-2\">ES0105089009 <\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">Espagne<\/td>\n<\/tr>\n<tr class=\"row-229 odd\">\n\t<td class=\"column-1\">LNA SANTE<\/td><td class=\"column-2\">FR0004170017<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-230 even\">\n\t<td class=\"column-1\">LUCIBEL<\/td><td class=\"column-2\">FR0011884378<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-231 odd\">\n\t<td class=\"column-1\">LUMIBIRD<\/td><td class=\"column-2\">FR0000038242<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-232 even\">\n\t<td class=\"column-1\">LYSOGENE SA<\/td><td class=\"column-2\">FR0013233475<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-233 odd\">\n\t<td class=\"column-1\">M2I<\/td><td class=\"column-2\">FR0013270626\u00a0<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-234 even\">\n\t<td class=\"column-1\">MADE<\/td><td class=\"column-2\">FR0010328302<\/td><td class=\"column-3\">Euronext Access<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-235 odd\">\n\t<td class=\"column-1\">MADVERTISE<\/td><td class=\"column-2\">FR0010812230<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-236 even\">\n\t<td class=\"column-1\">MAINSTAY MEDICAL \u00a0<\/td><td class=\"column-2\">IE00BJYS1G50<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-237 odd\">\n\t<td class=\"column-1\">MAKHEIA<\/td><td class=\"column-2\">FR0000072993<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-238 even\">\n\t<td class=\"column-1\">MANUTAN INTL<\/td><td class=\"column-2\">FR0000032302<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-239 odd\">\n\t<td class=\"column-1\">MARE NOSTRUM<\/td><td class=\"column-2\">FR0013400835<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-240 even\">\n\t<td class=\"column-1\">Marie Brizard Wine &amp; Spirits<\/td><td class=\"column-2\">FR0000060873<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-241 odd\">\n\t<td class=\"column-1\">MASTRAD<\/td><td class=\"column-2\">FR0004155687<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-242 even\">\n\t<td class=\"column-1\">MAUNA KEA TECH<\/td><td class=\"column-2\">FR0010609263<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-243 odd\">\n\t<td class=\"column-1\">MAUREL &amp; PROM<\/td><td class=\"column-2\">FR0000051070<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-244 even\">\n\t<td class=\"column-1\">MCPHY ENERGY<\/td><td class=\"column-2\">FR0011742329<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-245 odd\">\n\t<td class=\"column-1\">MEDESIS PHARMA<\/td><td class=\"column-2\">FR0010844464<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-246 even\">\n\t<td class=\"column-1\">MEDIAN TECHNOLOGIES<\/td><td class=\"column-2\">FR0011049824<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-247 odd\">\n\t<td class=\"column-1\">MEDINCELL<\/td><td class=\"column-2\">FR0004065605<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-248 even\">\n\t<td class=\"column-1\">MEMSCAP<\/td><td class=\"column-2\">FR0010298620<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-249 odd\">\n\t<td class=\"column-1\">METABOLIC EXPLORER<\/td><td class=\"column-2\">FR0004177046<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-250 even\">\n\t<td class=\"column-1\">METHANOR<\/td><td class=\"column-2\">FR0011217710<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-251 odd\">\n\t<td class=\"column-1\">METHORIOS CAPITAL<\/td><td class=\"column-2\">IT0004615396<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">Italie<\/td>\n<\/tr>\n<tr class=\"row-252 even\">\n\t<td class=\"column-1\">MGI DIGITAL GRAPHIC<\/td><td class=\"column-2\">FR0010353888<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-253 odd\">\n\t<td class=\"column-1\">MICROPOLE<\/td><td class=\"column-2\">FR0000077570<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-254 even\">\n\t<td class=\"column-1\">MIGUET ET ASSOCIES <\/td><td class=\"column-2\">FR0010500363<\/td><td class=\"column-3\">Euronext Access<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-255 odd\">\n\t<td class=\"column-1\">MILIBOO<\/td><td class=\"column-2\">FR0013053535<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-256 even\">\n\t<td class=\"column-1\">MINT<\/td><td class=\"column-2\">FR0004172450<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-257 odd\">\n\t<td class=\"column-1\">MND GROUP<\/td><td class=\"column-2\">FR0011584549<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-258 even\">\n\t<td class=\"column-1\">MOULINVEST<\/td><td class=\"column-2\">FR0011033083<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-259 odd\">\n\t<td class=\"column-1\">MR BRICOLAGE<\/td><td class=\"column-2\">FR0004034320<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-260 even\">\n\t<td class=\"column-1\">MUNIC<\/td><td class=\"column-2\">FR0013462231<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-261 odd\">\n\t<td class=\"column-1\">NACON<\/td><td class=\"column-2\">FR0013482791<\/td><td class=\"column-3\">Euronext <\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-262 even\">\n\t<td class=\"column-1\">NAMR SA<\/td><td class=\"column-2\">FR0014003J32<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-263 odd\">\n\t<td class=\"column-1\">NANOBIOTIX<\/td><td class=\"column-2\">FR0011341205<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-264 even\">\n\t<td class=\"column-1\">NATURE ET LOGIS<\/td><td class=\"column-2\">FR0013344223<\/td><td class=\"column-3\">Euronext Access<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-265 odd\">\n\t<td class=\"column-1\">NEOVACS<\/td><td class=\"column-2\">FR0004032746<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-266 even\">\n\t<td class=\"column-1\">NETGEM<\/td><td class=\"column-2\">FR0004154060<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-267 odd\">\n\t<td class=\"column-1\">NEXTEDIA<\/td><td class=\"column-2\">FR0004171346<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-268 even\">\n\t<td class=\"column-1\">NFL BIOSCIENCES<\/td><td class=\"column-2\">FR0014003XT0<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">FRANCE<\/td>\n<\/tr>\n<tr class=\"row-269 odd\">\n\t<td class=\"column-1\">NICOX<\/td><td class=\"column-2\">FR0013018124<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-270 even\">\n\t<td class=\"column-1\">NOVACYT<\/td><td class=\"column-2\">FR0010397232<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-271 odd\">\n\t<td class=\"column-1\">NRJ GROUP<\/td><td class=\"column-2\">FR0000121691<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-272 even\">\n\t<td class=\"column-1\">OBER<\/td><td class=\"column-2\">FR0010330613<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-273 odd\">\n\t<td class=\"column-1\">OBIZ<\/td><td class=\"column-2\">FR0014003711<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-274 even\">\n\t<td class=\"column-1\">OCEASOFT<\/td><td class=\"column-2\">FR0012407096<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-275 odd\">\n\t<td class=\"column-1\">OCTOPUS BIOSAFETY<\/td><td class=\"column-2\">FR0013310281<\/td><td class=\"column-3\">Euronext Access<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-276 even\">\n\t<td class=\"column-1\">OMER-DECUGIS &amp; CIE<\/td><td class=\"column-2\">FR0014003T71<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-277 odd\">\n\t<td class=\"column-1\">ONCODESIGN<\/td><td class=\"column-2\">FR0011766229<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-278 even\">\n\t<td class=\"column-1\">ONE EXPERIENCE<\/td><td class=\"column-2\">FR0013266772<\/td><td class=\"column-3\">Euronext Access<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-279 odd\">\n\t<td class=\"column-1\">ONXEO<\/td><td class=\"column-2\">FR0010095596<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-280 even\">\n\t<td class=\"column-1\">ORAPI<\/td><td class=\"column-2\">FR0000075392<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-281 odd\">\n\t<td class=\"column-1\">ORCHESTRA PREMAMAN<\/td><td class=\"column-2\">FR0013190410<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-282 even\">\n\t<td class=\"column-1\">ORDISSIMO<\/td><td class=\"column-2\">FR0013318052<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-283 odd\">\n\t<td class=\"column-1\">OREGE<\/td><td class=\"column-2\">FR0010609206<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-284 even\">\n\t<td class=\"column-1\">OSE IMMUNO<\/td><td class=\"column-2\">FR0012127173<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-285 odd\">\n\t<td class=\"column-1\">OSMOZIS<\/td><td class=\"column-2\">FR0013231180<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-286 even\">\n\t<td class=\"column-1\">PARFEX<\/td><td class=\"column-2\">FR0000185928<\/td><td class=\"column-3\">Euronext Access<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-287 odd\">\n\t<td class=\"column-1\">PARROT<\/td><td class=\"column-2\">FR0004038263<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-288 even\">\n\t<td class=\"column-1\">PAULIC MEUNERIE<\/td><td class=\"column-2\">FR0013479730<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-289 odd\">\n\t<td class=\"column-1\">PCAS<\/td><td class=\"column-2\">FR0000053514<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-290 even\">\n\t<td class=\"column-1\">PHARMAGEST INTERACTIVE<\/td><td class=\"column-2\">FR0012882389<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-291 odd\">\n\t<td class=\"column-1\">PHARNEXT<\/td><td class=\"column-2\">FR0011191287<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-292 even\">\n\t<td class=\"column-1\">PHERECYDES PHARMA<\/td><td class=\"column-2\">FR0011651694<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-293 odd\">\n\t<td class=\"column-1\">PIXIUM VISION<\/td><td class=\"column-2\">FR0011950641<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-294 even\">\n\t<td class=\"column-1\">PLANET MEDIA<\/td><td class=\"column-2\">FR0010211037<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-295 odd\">\n\t<td class=\"column-1\">PLANT ADVANCED T.<\/td><td class=\"column-2\">FR0010785790<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-296 even\">\n\t<td class=\"column-1\">PLAST.VAL LOIRE <\/td><td class=\"column-2\">FR0013252186<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-297 odd\">\n\t<td class=\"column-1\">POUJOULAT<\/td><td class=\"column-2\">FR0000066441<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-298 even\">\n\t<td class=\"column-1\">POULAILLON<\/td><td class=\"column-2\">FR0013015583<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-299 odd\">\n\t<td class=\"column-1\">POXEL<\/td><td class=\"column-2\">FR0012432516<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-300 even\">\n\t<td class=\"column-1\">PRECIA<\/td><td class=\"column-2\">FR0000060832<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-301 odd\">\n\t<td class=\"column-1\">PREDILIFE<\/td><td class=\"column-2\">FR0010169920\u00a0<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-302 even\">\n\t<td class=\"column-1\">PRISMAFLEX INTERNATIONAL<\/td><td class=\"column-2\">FR0004044600<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-303 odd\">\n\t<td class=\"column-1\">PRODWARE<\/td><td class=\"column-2\">FR0010313486<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-304 even\">\n\t<td class=\"column-1\">PRODWAYS<\/td><td class=\"column-2\">FR0012613610<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-305 odd\">\n\t<td class=\"column-1\">PROLOGUE<\/td><td class=\"column-2\">FR0010380626<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-306 even\">\n\t<td class=\"column-1\">QUANTUM GENOMICS<\/td><td class=\"column-2\">FR0011648971<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-307 odd\">\n\t<td class=\"column-1\">QWAMPLIFY<\/td><td class=\"column-2\">FR0010889386<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-308 even\">\n\t<td class=\"column-1\">REALITES<\/td><td class=\"column-2\">FR0011858190<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-309 odd\">\n\t<td class=\"column-1\">REWORLD MEDIA<\/td><td class=\"column-2\">FR0010820274<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-310 even\">\n\t<td class=\"column-1\">RIBER<\/td><td class=\"column-2\">FR0000075954<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-311 odd\">\n\t<td class=\"column-1\">ROBERTET SA<\/td><td class=\"column-2\">FR0000039091<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">A<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-312 even\">\n\t<td class=\"column-1\">ROCHE BOBOIS<\/td><td class=\"column-2\">FR0013344173<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-313 odd\">\n\t<td class=\"column-1\">ROCTOOL<\/td><td class=\"column-2\">FR0010523167<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-314 even\">\n\t<td class=\"column-1\">ROUGIER<\/td><td class=\"column-2\">FR0000037640<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-315 odd\">\n\t<td class=\"column-1\">SAFE ORTHOPAEDICS<\/td><td class=\"column-2\">FR0012452746<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-316 even\">\n\t<td class=\"column-1\">SAINT JEAN GROUPE (EX. SABETON)<\/td><td class=\"column-2\">FR0000060121<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-317 odd\">\n\t<td class=\"column-1\">SBT<\/td><td class=\"column-2\">FR0004175222<\/td><td class=\"column-3\">Euronext Access<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-318 even\">\n\t<td class=\"column-1\">SECHE ENVIRONNEMENT<\/td><td class=\"column-2\">FR0000039109<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-319 odd\">\n\t<td class=\"column-1\">SENSORION<\/td><td class=\"column-2\">FR0012596468<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-320 even\">\n\t<td class=\"column-1\">SERGEFERRARI GROUP<\/td><td class=\"column-2\">FR0011950682<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-321 odd\">\n\t<td class=\"column-1\">SES IMAGOTAG<\/td><td class=\"column-2\">FR0010282822<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-322 even\">\n\t<td class=\"column-1\">SHOWROOMPRIVE<\/td><td class=\"column-2\">FR0013006558<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-323 odd\">\n\t<td class=\"column-1\">SIDETRADE<\/td><td class=\"column-2\">FR0010202606<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-324 even\">\n\t<td class=\"column-1\">SIGNAUX GIROD<\/td><td class=\"column-2\">FR0000060790<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-325 odd\">\n\t<td class=\"column-1\">SII<\/td><td class=\"column-2\">FR0000074122<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-326 even\">\n\t<td class=\"column-1\">SOGECLAIR<\/td><td class=\"column-2\">FR0000065864<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-327 odd\">\n\t<td class=\"column-1\">SOITEC<\/td><td class=\"column-2\">FR0013227113<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">A<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-328 even\">\n\t<td class=\"column-1\">SOLOCAL GOUP<\/td><td class=\"column-2\">FR00140006O9<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-329 odd\">\n\t<td class=\"column-1\">SOLUTIONS 30 SE<\/td><td class=\"column-2\">FR0013379484<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">A<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-330 even\">\n\t<td class=\"column-1\">SPARTOO<\/td><td class=\"column-2\">FR00140043Y1<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-331 odd\">\n\t<td class=\"column-1\">SPINEGUARD<\/td><td class=\"column-2\">FR0011464452<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-332 even\">\n\t<td class=\"column-1\">SPINEWAY<\/td><td class=\"column-2\">FR0011398874<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-333 odd\">\n\t<td class=\"column-1\">SQLI<\/td><td class=\"column-2\">FR0011289040<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-334 even\">\n\t<td class=\"column-1\">STRADIM ESPACE FINANCES<\/td><td class=\"column-2\">FR0000074775<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-335 odd\">\n\t<td class=\"column-1\">STREAMWIDE<\/td><td class=\"column-2\">FR0010528059<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-336 even\">\n\t<td class=\"column-1\">SWORD GROUP<\/td><td class=\"column-2\">FR0004180578<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">Luxembourg<\/td>\n<\/tr>\n<tr class=\"row-337 odd\">\n\t<td class=\"column-1\">TESSI<\/td><td class=\"column-2\">FR0004529147<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-338 even\">\n\t<td class=\"column-1\">TFF GROUP<\/td><td class=\"column-2\">FR0013295789<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-339 odd\">\n\t<td class=\"column-1\">THE BLOCKCHAIN GP<\/td><td class=\"column-2\">FR0011053636<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-340 even\">\n\t<td class=\"column-1\">THERACLION<\/td><td class=\"column-2\">FR0010120402<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-341 odd\">\n\t<td class=\"column-1\">THERADIAG<\/td><td class=\"column-2\">FR0004197747<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-342 even\">\n\t<td class=\"column-1\">THERANEXUS<\/td><td class=\"column-2\">FR0013286259<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-343 odd\">\n\t<td class=\"column-1\">THERAVET SA<\/td><td class=\"column-2\">BE0974387194<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">Belgique<\/td>\n<\/tr>\n<tr class=\"row-344 even\">\n\t<td class=\"column-1\">THERMADOR GROUPE<\/td><td class=\"column-2\">FR0013333432<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-345 odd\">\n\t<td class=\"column-1\">TIPIAK<\/td><td class=\"column-2\">FR0000066482<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-346 even\">\n\t<td class=\"column-1\">TIVOLY<\/td><td class=\"column-2\">FR0000060949<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-347 odd\">\n\t<td class=\"column-1\">TOUAX<\/td><td class=\"column-2\">FR0000033003<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-348 even\">\n\t<td class=\"column-1\">TRIGANO<\/td><td class=\"column-2\">FR0005691656<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">A<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-349 odd\">\n\t<td class=\"column-1\">TRONICS <\/td><td class=\"column-2\">FR0004175099<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-350 even\">\n\t<td class=\"column-1\">U10 CORP<\/td><td class=\"column-2\">FR0000079147<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-351 odd\">\n\t<td class=\"column-1\">UCAR<\/td><td class=\"column-2\">FR0011070457<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-352 even\">\n\t<td class=\"column-1\">UMANIS<\/td><td class=\"column-2\">FR0013263878<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-353 odd\">\n\t<td class=\"column-1\">UNITI<\/td><td class=\"column-2\">FR0012709160 <\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-354 even\">\n\t<td class=\"column-1\">UPERGY<\/td><td class=\"column-2\">FR0010337865<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-355 odd\">\n\t<td class=\"column-1\">UV GERMI<\/td><td class=\"column-2\">FR0011898584<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-356 even\">\n\t<td class=\"column-1\">VALBIOTIS<\/td><td class=\"column-2\">FR0013254851<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-357 odd\">\n\t<td class=\"column-1\">VALNEVA<\/td><td class=\"column-2\">FR0004056851<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-358 even\">\n\t<td class=\"column-1\">VELCAN HOLDINGS<\/td><td class=\"column-2\">FR0010245803<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-359 odd\">\n\t<td class=\"column-1\">VENTE-UNIQUE.COM<\/td><td class=\"column-2\">FR0010766667<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-360 even\">\n\t<td class=\"column-1\">VERIMATRIX<\/td><td class=\"column-2\">FR0010291245<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">C<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-361 odd\">\n\t<td class=\"column-1\">VERNEY-CARRON <\/td><td class=\"column-2\">FR0006174496<\/td><td class=\"column-3\">Euronext Access<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-362 even\">\n\t<td class=\"column-1\">VETOQUINOL<\/td><td class=\"column-2\">FR0004186856<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-363 odd\">\n\t<td class=\"column-1\">VIRBAC<\/td><td class=\"column-2\">FR0000031577<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">A<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-364 even\">\n\t<td class=\"column-1\">VISIATIV<\/td><td class=\"column-2\">FR0004029478<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-365 odd\">\n\t<td class=\"column-1\">VISIOMED GROUP <\/td><td class=\"column-2\">FR0013481835 <\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-366 even\">\n\t<td class=\"column-1\">VOGO<\/td><td class=\"column-2\">\u00a0FR0011532225<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-367 odd\">\n\t<td class=\"column-1\">VOLUNTIS<\/td><td class=\"column-2\">FR0004183960<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-368 even\">\n\t<td class=\"column-1\">VOYAGEURS DU MONDE<\/td><td class=\"column-2\">FR0004045847<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-369 odd\">\n\t<td class=\"column-1\">VRANKEN-POMMERY<\/td><td class=\"column-2\">FR0000062796<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-370 even\">\n\t<td class=\"column-1\">WALLIX<\/td><td class=\"column-2\">FR0010131409<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-371 odd\">\n\t<td class=\"column-1\">WAVESTONE<\/td><td class=\"column-2\">FR0013357621<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-372 even\">\n\t<td class=\"column-1\">WE.CONNECT<\/td><td class=\"column-2\">FR0013079092<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-373 odd\">\n\t<td class=\"column-1\">WEACCESS<\/td><td class=\"column-2\">FR0010688465<\/td><td class=\"column-3\">Euronext Access<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-374 even\">\n\t<td class=\"column-1\">WINFARM<\/td><td class=\"column-2\">FR0014000P11<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-375 odd\">\n\t<td class=\"column-1\">WITBE<\/td><td class=\"column-2\">FR0013143872<\/td><td class=\"column-3\">Euronext Growth<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-376 even\">\n\t<td class=\"column-1\">WIZIBOAT<\/td><td class=\"column-2\">FR00140047H7<\/td><td class=\"column-3\">Euronext Access<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<tr class=\"row-377 odd\">\n\t<td class=\"column-1\">XILAM<\/td><td class=\"column-2\">FR0004034072<\/td><td class=\"column-3\">Euronext<\/td><td class=\"column-4\">B<\/td><td class=\"column-5\">France<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n<\/div><!-- #tablepress-46 from cache -->\n<p>Cette liste est g\u00e9n\u00e9ralement (mais pas syst\u00e9matiquement) celle utilis\u00e9e par les courtiers de Bourse en ligne pour d\u00e9terminer les titres qu\u2019il est possible de n\u00e9gocier sur leur plateforme au sein d\u2019un PEA-PME.<\/p>\n<p>Par exemple, EasyBourse sur fonde sur la liste de son fournisseur de donn\u00e9es Six Group (pas exactement la m\u00eame que celle d&rsquo;Euronext). La liste des titres \u00e9ligibles chez le courtier en ligne de La Banque Postale est la suivante :<\/p>\n<div id=\"tablepress-48-scroll-wrapper\" class=\"tablepress-scroll-wrapper\">\n\n<table id=\"tablepress-48\" class=\"tablepress tablepress-id-48 tablepress-responsive\">\n<thead>\n<tr class=\"row-1 odd\">\n\t<th class=\"column-1\">CODE Isin<\/th><th class=\"column-2\">Libell\u00e9<\/th><th class=\"column-3\">Place de cotation<\/th>\n<\/tr>\n<\/thead>\n<tfoot>\n<tr class=\"row-416 even\">\n\t<th class=\"column-1\">Source : Easybourse (au 22\/07\/2021)<\/th><th class=\"column-2\">#colspan<\/th><th class=\"column-3\">#colspan<\/th>\n<\/tr>\n<\/tfoot>\n<tbody class=\"row-hover\">\n<tr class=\"row-2 even\">\n\t<td class=\"column-1\">FR0010285965<\/td><td class=\"column-2\">1000MERCIS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-3 odd\">\n\t<td class=\"column-1\">FR0013341781<\/td><td class=\"column-2\">2CRSI<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-4 even\">\n\t<td class=\"column-1\">FR0000076887<\/td><td class=\"column-2\">A.S.T GROUPE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-5 odd\">\n\t<td class=\"column-1\">FR0010557264<\/td><td class=\"column-2\">AB SCIENCE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-6 even\">\n\t<td class=\"column-1\">FR0004040608<\/td><td class=\"column-2\">ABC ARBITRAGE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-7 odd\">\n\t<td class=\"column-1\">FR0013185857<\/td><td class=\"column-2\">ABEO<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-8 even\">\n\t<td class=\"column-1\">FR0012616852<\/td><td class=\"column-2\">ABIONYX PHARMA SA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-9 odd\">\n\t<td class=\"column-1\">FR0012333284<\/td><td class=\"column-2\">ABIVAX<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-10 even\">\n\t<td class=\"column-1\">FR0000076861<\/td><td class=\"column-2\">ACTEOS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-11 odd\">\n\t<td class=\"column-1\">FR0000076655<\/td><td class=\"column-2\">ACTIA GROUP<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-12 even\">\n\t<td class=\"column-1\">FR0013284627<\/td><td class=\"column-2\">ADEUNIS RF<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-13 odd\">\n\t<td class=\"column-1\">FR0000062978<\/td><td class=\"column-2\">ADLPARTNER<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-14 even\">\n\t<td class=\"column-1\">FR0011184241<\/td><td class=\"column-2\">ADOCIA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-15 odd\">\n\t<td class=\"column-1\">FR0013247244<\/td><td class=\"column-2\">ADOMOS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-16 even\">\n\t<td class=\"column-1\">FR0010457531<\/td><td class=\"column-2\">ADTHINK<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-17 odd\">\n\t<td class=\"column-1\">FR0012821890<\/td><td class=\"column-2\">ADUX SA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-18 even\">\n\t<td class=\"column-1\">FR0004152874<\/td><td class=\"column-2\">ADVENIS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-19 odd\">\n\t<td class=\"column-1\">FR0013296746<\/td><td class=\"column-2\">ADVICENNE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-20 even\">\n\t<td class=\"column-1\">FR0000053043<\/td><td class=\"column-2\">ADVINI<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-21 odd\">\n\t<td class=\"column-1\">FR0013333077<\/td><td class=\"column-2\">AFFLUENT MED<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-22 even\">\n\t<td class=\"column-1\">FR0014003I41<\/td><td class=\"column-2\">AGENCES DE PAPA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-23 odd\">\n\t<td class=\"column-1\">FR0013452281<\/td><td class=\"column-2\">AGRIPOWER FCE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-24 even\">\n\t<td class=\"column-1\">FR0013285103<\/td><td class=\"column-2\">AIR MARINE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-25 odd\">\n\t<td class=\"column-1\">FR0000060402<\/td><td class=\"column-2\">ALBIOMA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-26 even\">\n\t<td class=\"column-1\">FR0014000JX7<\/td><td class=\"column-2\">ALCHIMIE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-27 odd\">\n\t<td class=\"column-1\">FR0000054652<\/td><td class=\"column-2\">ALES GROUPE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-28 even\">\n\t<td class=\"column-1\">FR0013421286<\/td><td class=\"column-2\">ALPHA MOS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-29 odd\">\n\t<td class=\"column-1\">FR0000061244<\/td><td class=\"column-2\">ALTHEORA SA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-30 even\">\n\t<td class=\"column-1\">FR0010395681<\/td><td class=\"column-2\">ALTUR INVESTISSEMENT<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-31 odd\">\n\t<td class=\"column-1\">FR0011051598<\/td><td class=\"column-2\">AMOEBA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-32 even\">\n\t<td class=\"column-1\">FR0012789667<\/td><td class=\"column-2\">AMPLITUDE SURGICAL<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-33 odd\">\n\t<td class=\"column-1\">ES0109429037<\/td><td class=\"column-2\">ANTEVENIO<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-34 even\">\n\t<td class=\"column-1\">FR0010340711<\/td><td class=\"column-2\">AQUILA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-35 odd\">\n\t<td class=\"column-1\">FR0000182479<\/td><td class=\"column-2\">ARCHOS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-36 even\">\n\t<td class=\"column-1\">FR0013398997<\/td><td class=\"column-2\">ARCURE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-37 odd\">\n\t<td class=\"column-1\">FR0012185536<\/td><td class=\"column-2\">ARTEA REGROUPEES<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-38 even\">\n\t<td class=\"column-1\">FR0000079683<\/td><td class=\"column-2\">ARTEFACT<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-39 odd\">\n\t<td class=\"column-1\">FR0000074783<\/td><td class=\"column-2\">ARTMARKET COM SA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-40 even\">\n\t<td class=\"column-1\">FR0012968485<\/td><td class=\"column-2\">ASHLER ET MANSON<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-41 odd\">\n\t<td class=\"column-1\">BE0974289218<\/td><td class=\"column-2\">ASIT BIOTECH<\/td><td class=\"column-3\">Euronext Bruxelles<\/td>\n<\/tr>\n<tr class=\"row-42 even\">\n\t<td class=\"column-1\">FR0010478248<\/td><td class=\"column-2\">ATARI<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-43 odd\">\n\t<td class=\"column-1\">FR0011992700<\/td><td class=\"column-2\">ATEME<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-44 even\">\n\t<td class=\"column-1\">BE0003837540<\/td><td class=\"column-2\">ATENOR<\/td><td class=\"column-3\">Euronext Bruxelles<\/td>\n<\/tr>\n<tr class=\"row-45 odd\">\n\t<td class=\"column-1\">FR0011896463<\/td><td class=\"column-2\">AUDIENCE LABS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-46 even\">\n\t<td class=\"column-1\">BE0974334667<\/td><td class=\"column-2\">AUDIOVALLEY RG<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-47 odd\">\n\t<td class=\"column-1\">FR0000061780<\/td><td class=\"column-2\">AUGROS CP<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-48 even\">\n\t<td class=\"column-1\">FR0013410370<\/td><td class=\"column-2\">AUPLATA MINING GROUP AMG<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-49 odd\">\n\t<td class=\"column-1\">FR0000039232<\/td><td class=\"column-2\">AUREA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-50 even\">\n\t<td class=\"column-1\">FR0013183589<\/td><td class=\"column-2\">AURES TECHNOLOGIES<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-51 odd\">\n\t<td class=\"column-1\">FR0013529815<\/td><td class=\"column-2\">AVENIR TELECOM<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-52 even\">\n\t<td class=\"column-1\">FR0011040500<\/td><td class=\"column-2\">AXWAY SOFTWARE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-53 odd\">\n\t<td class=\"column-1\">FR0013384369<\/td><td class=\"column-2\">BAIKOWSKI<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-54 even\">\n\t<td class=\"column-1\">FR0013258399<\/td><td class=\"column-2\">BALYO<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-55 odd\">\n\t<td class=\"column-1\">FR0000062788<\/td><td class=\"column-2\">BARBARA BUI<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-56 even\">\n\t<td class=\"column-1\">BE0974362940<\/td><td class=\"column-2\">BARCO<\/td><td class=\"column-3\">Euronext Bruxelles<\/td>\n<\/tr>\n<tr class=\"row-57 odd\">\n\t<td class=\"column-1\">FR0004023208<\/td><td class=\"column-2\">BASSAC SA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-58 even\">\n\t<td class=\"column-1\">FR0000035370<\/td><td class=\"column-2\">BASTIDE LE CONFORT MEDICAL<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-59 odd\">\n\t<td class=\"column-1\">FR0000035305<\/td><td class=\"column-2\">BD MULTI-MEDIA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-60 even\">\n\t<td class=\"column-1\">NL0012866412<\/td><td class=\"column-2\">BE SEMICONDUCTOR INDUSTRIES<\/td><td class=\"column-3\">Euronext Amsterdam<\/td>\n<\/tr>\n<tr class=\"row-61 odd\">\n\t<td class=\"column-1\">FR0000074072<\/td><td class=\"column-2\">BIGBEN INTERACTIVE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-62 even\">\n\t<td class=\"column-1\">FR0004174233<\/td><td class=\"column-2\">BILENDI SA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-63 odd\">\n\t<td class=\"column-1\">FR0012788065<\/td><td class=\"column-2\">BIOCORP PRODUCTION<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-64 even\">\n\t<td class=\"column-1\">FR0012816825<\/td><td class=\"column-2\">BIOPHYTIS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-65 odd\">\n\t<td class=\"column-1\">FR0011005933<\/td><td class=\"column-2\">BIOSYNEX<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-66 even\">\n\t<td class=\"column-1\">FR0013345493<\/td><td class=\"column-2\">BIO-UV GRP<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-67 odd\">\n\t<td class=\"column-1\">FR0013340973<\/td><td class=\"column-2\">BLUE SHARK PS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-68 even\">\n\t<td class=\"column-1\">FR0011041011<\/td><td class=\"column-2\">BLUELINEA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-69 odd\">\n\t<td class=\"column-1\">FR0011365907<\/td><td class=\"column-2\">BOA CONCEPT<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-70 even\">\n\t<td class=\"column-1\">FR0010106039<\/td><td class=\"column-2\">BODY ONE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-71 odd\">\n\t<td class=\"column-1\">BE0974280126<\/td><td class=\"column-2\">BONE THERAPEUTICS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-72 even\">\n\t<td class=\"column-1\">BE0974280126<\/td><td class=\"column-2\">BONE THERAPEUTICS<\/td><td class=\"column-3\">Euronext Bruxelles<\/td>\n<\/tr>\n<tr class=\"row-73 odd\">\n\t<td class=\"column-1\">FR0011814938<\/td><td class=\"column-2\">BOOSTHEAT<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-74 even\">\n\t<td class=\"column-1\">FR0000054421<\/td><td class=\"column-2\">BOURRELIER GROUP SA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-75 odd\">\n\t<td class=\"column-1\">FR0000074254<\/td><td class=\"column-2\">BOURSE DIRECT<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-76 even\">\n\t<td class=\"column-1\">FR0013530102<\/td><td class=\"column-2\">CABASSE GROUP<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-77 odd\">\n\t<td class=\"column-1\">FR0010151589<\/td><td class=\"column-2\">CAFOM<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-78 even\">\n\t<td class=\"column-1\">BE0974298300<\/td><td class=\"column-2\">CANDELA INVEST<\/td><td class=\"column-3\">Euronext Bruxelles<\/td>\n<\/tr>\n<tr class=\"row-79 odd\">\n\t<td class=\"column-1\">FR0012969095<\/td><td class=\"column-2\">CAPELLI<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-80 even\">\n\t<td class=\"column-1\">FR0011648716<\/td><td class=\"column-2\">CARBIOS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-81 odd\">\n\t<td class=\"column-1\">FR0010907956<\/td><td class=\"column-2\">CARMAT<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-82 even\">\n\t<td class=\"column-1\">FR0000072894<\/td><td class=\"column-2\">CAST<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-83 odd\">\n\t<td class=\"column-1\">FR0010193052<\/td><td class=\"column-2\">CATANA GROUP SA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-84 even\">\n\t<td class=\"column-1\">FR0010193979<\/td><td class=\"column-2\">CBO TERRITORIA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-85 odd\">\n\t<td class=\"column-1\">FR0010425595<\/td><td class=\"column-2\">CELLECTIS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-86 even\">\n\t<td class=\"column-1\">BE0974260896<\/td><td class=\"column-2\">CELYAD ONCOLOGY S.A.<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-87 odd\">\n\t<td class=\"column-1\">BE0974260896<\/td><td class=\"column-2\">CELYAD ONCOLOGY S.A.<\/td><td class=\"column-3\">Euronext Bruxelles<\/td>\n<\/tr>\n<tr class=\"row-88 even\">\n\t<td class=\"column-1\">FR0013178712<\/td><td class=\"column-2\">CERINNOV GROUP<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-89 odd\">\n\t<td class=\"column-1\">FR0000130692<\/td><td class=\"column-2\">CHARGEURS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-90 even\">\n\t<td class=\"column-1\">FR0000060907<\/td><td class=\"column-2\">CHAUSSERIA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-91 odd\">\n\t<td class=\"column-1\">FR0000054322<\/td><td class=\"column-2\">CIBOX INTER@CTIVE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-92 even\">\n\t<td class=\"column-1\">FR0013426004<\/td><td class=\"column-2\">CLARANOVA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-93 odd\">\n\t<td class=\"column-1\">FR0004152882<\/td><td class=\"column-2\">CLASQUIN<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-94 even\">\n\t<td class=\"column-1\">FR0013257409<\/td><td class=\"column-2\">COFIDUR<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-95 odd\">\n\t<td class=\"column-1\">FR0013335742<\/td><td class=\"column-2\">COGELEC<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-96 even\">\n\t<td class=\"column-1\">FR0011071570<\/td><td class=\"column-2\">COGRA 48<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-97 odd\">\n\t<td class=\"column-1\">FR0000060428<\/td><td class=\"column-2\">COMPAGNIE DU MONT-BLANC<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-98 even\">\n\t<td class=\"column-1\">FR0000121295<\/td><td class=\"column-2\">COMPAGNIE LEBON<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-99 odd\">\n\t<td class=\"column-1\">FR0000065393<\/td><td class=\"column-2\">COURTOIS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-100 even\">\n\t<td class=\"column-1\">FR0011716265<\/td><td class=\"column-2\">CROSSJECT<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-101 odd\">\n\t<td class=\"column-1\">FR0000050395<\/td><td class=\"column-2\">CROSSWOOD<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-102 even\">\n\t<td class=\"column-1\">FR0007317813<\/td><td class=\"column-2\">CS GROUP<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-103 odd\">\n\t<td class=\"column-1\">FR0013505583<\/td><td class=\"column-2\">CYBERGUN<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-104 even\">\n\t<td class=\"column-1\">FR0010404368<\/td><td class=\"column-2\">D.L.S.I.<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-105 odd\">\n\t<td class=\"column-1\">FR0000185423<\/td><td class=\"column-2\">DAMARTEX<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-106 even\">\n\t<td class=\"column-1\">FR0013066750<\/td><td class=\"column-2\">DBT<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-107 odd\">\n\t<td class=\"column-1\">FR0010417345<\/td><td class=\"column-2\">DBV TECHNOLOGIES<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-108 even\">\n\t<td class=\"column-1\">FR0010879056<\/td><td class=\"column-2\">DEINOVE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-109 odd\">\n\t<td class=\"column-1\">FR0000054132<\/td><td class=\"column-2\">DELFINGEN INDUSTRY<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-110 even\">\n\t<td class=\"column-1\">FR0011522168<\/td><td class=\"column-2\">DELTA DRONE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-111 odd\">\n\t<td class=\"column-1\">FR0013283108<\/td><td class=\"column-2\">DELTA PLUS GROUP<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-112 even\">\n\t<td class=\"column-1\">FR0000073793<\/td><td class=\"column-2\">DEVOTEAM<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-113 odd\">\n\t<td class=\"column-1\">FR0012202497<\/td><td class=\"column-2\">DIAGNOSTIC MEDICAL SYSTEMS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-114 even\">\n\t<td class=\"column-1\">FR0010436584<\/td><td class=\"column-2\">DNXCORP<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-115 odd\">\n\t<td class=\"column-1\">FR0010377127<\/td><td class=\"column-2\">DOLFINES SA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-116 even\">\n\t<td class=\"column-1\">FR0013331212<\/td><td class=\"column-2\">DONTNOD<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-117 odd\">\n\t<td class=\"column-1\">FR0013088606<\/td><td class=\"column-2\">DRONE VOLT<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-118 even\">\n\t<td class=\"column-1\">FR0013534617<\/td><td class=\"column-2\">ECOMIAM<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-119 odd\">\n\t<td class=\"column-1\">FR0011490648<\/td><td class=\"column-2\">ECOSLOPS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-120 even\">\n\t<td class=\"column-1\">IT0005351504<\/td><td class=\"column-2\">EDILIZIACROB P N<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-121 odd\">\n\t<td class=\"column-1\">FR0000072373<\/td><td class=\"column-2\">EGIDE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-122 even\">\n\t<td class=\"column-1\">FR0011466069<\/td><td class=\"column-2\">EKINOPS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-123 odd\">\n\t<td class=\"column-1\">FR0013356755<\/td><td class=\"column-2\">EMOVA GROUP SA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-124 even\">\n\t<td class=\"column-1\">FR0004030708<\/td><td class=\"column-2\">ENCRES DUBUIT<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-125 odd\">\n\t<td class=\"column-1\">FR0013330792<\/td><td class=\"column-2\">ENENSYS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-126 even\">\n\t<td class=\"column-1\">FR0013399359<\/td><td class=\"column-2\">ENERGISME<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-127 odd\">\n\t<td class=\"column-1\">FR0011915339<\/td><td class=\"column-2\">ENERTIME<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-128 even\">\n\t<td class=\"column-1\">FR0014004974<\/td><td class=\"column-2\">ENOGIA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-129 odd\">\n\t<td class=\"column-1\">FR0010424697<\/td><td class=\"column-2\">ENTREPARTICULIERS.COM<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-130 even\">\n\t<td class=\"column-1\">FR0010278762<\/td><td class=\"column-2\">ENVEA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-131 odd\">\n\t<td class=\"column-1\">FR0010465534<\/td><td class=\"column-2\">EO2<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-132 even\">\n\t<td class=\"column-1\">FR0014004339<\/td><td class=\"column-2\">E-PANGO<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-133 odd\">\n\t<td class=\"column-1\">FR0011471135<\/td><td class=\"column-2\">ERYTECH PHARMA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-134 even\">\n\t<td class=\"column-1\">FR0004110310<\/td><td class=\"column-2\">ESI GROUP<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-135 odd\">\n\t<td class=\"column-1\">FR0000035818<\/td><td class=\"column-2\">ESKER<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-136 even\">\n\t<td class=\"column-1\">FR0013240934<\/td><td class=\"column-2\">EUROBIO SCIENTIFIC<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-137 odd\">\n\t<td class=\"column-1\">FR0010452474<\/td><td class=\"column-2\">EUROGERM<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-138 even\">\n\t<td class=\"column-1\">FR0000075343<\/td><td class=\"column-2\">EUROMEDIS GROUPE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-139 odd\">\n\t<td class=\"column-1\">FR0013514114<\/td><td class=\"column-2\">EUROPLASMA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-140 even\">\n\t<td class=\"column-1\">FR0010221234<\/td><td class=\"column-2\">EUTELSAT COMMUNICATIONS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-141 odd\">\n\t<td class=\"column-1\">FR0004166197<\/td><td class=\"column-2\">EVOLIS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-142 even\">\n\t<td class=\"column-1\">BE0003820371<\/td><td class=\"column-2\">EVS BROADCAST EQUIPMENT<\/td><td class=\"column-3\">Euronext Bruxelles<\/td>\n<\/tr>\n<tr class=\"row-143 odd\">\n\t<td class=\"column-1\">FR0000064164<\/td><td class=\"column-2\">EXACOMPTA CLAIREFONTAINE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-144 even\">\n\t<td class=\"column-1\">FR0004527638<\/td><td class=\"column-2\">EXEL INDUSTRIES<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-145 odd\">\n\t<td class=\"column-1\">FR0014003AQ4<\/td><td class=\"column-2\">EXPLOSIFS ET PDT CHIMIQUES<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-146 even\">\n\t<td class=\"column-1\">FR0012300424<\/td><td class=\"column-2\">FD<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-147 odd\">\n\t<td class=\"column-1\">FR0011271600<\/td><td class=\"column-2\">FERMENTALG<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-148 even\">\n\t<td class=\"column-1\">FR0000062341<\/td><td class=\"column-2\">FIEBM<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-149 odd\">\n\t<td class=\"column-1\">FR0011665280<\/td><td class=\"column-2\">FIGEAC AERO<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-150 even\">\n\t<td class=\"column-1\">FR0010221069<\/td><td class=\"column-2\">FILAE SA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-151 odd\">\n\t<td class=\"column-1\">FR0000074759<\/td><td class=\"column-2\">FLEURY MICHON<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-152 even\">\n\t<td class=\"column-1\">FR0012419307<\/td><td class=\"column-2\">FOCUS HOME INTERACTIVE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-153 odd\">\n\t<td class=\"column-1\">FR0000053944<\/td><td class=\"column-2\">FONCIERE VOLTA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-154 even\">\n\t<td class=\"column-1\">FR0010485268<\/td><td class=\"column-2\">FOUNTAINE PAJOT<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-155 odd\">\n\t<td class=\"column-1\">FR0004187367<\/td><td class=\"column-2\">FREELANCE.COM<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-156 even\">\n\t<td class=\"column-1\">FR0000124414<\/td><td class=\"column-2\">GASCOGNE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-157 odd\">\n\t<td class=\"column-1\">FR0000034894<\/td><td class=\"column-2\">GAUMONT<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-158 even\">\n\t<td class=\"column-1\">FR0013495298<\/td><td class=\"column-2\">GAUSSIN<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-159 odd\">\n\t<td class=\"column-1\">FR0000079634<\/td><td class=\"column-2\">GECI INTERNATIONAL<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-160 even\">\n\t<td class=\"column-1\">FR0010501692<\/td><td class=\"column-2\">GENERIX GROUP<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-161 odd\">\n\t<td class=\"column-1\">FR0004163111<\/td><td class=\"column-2\">GENFIT<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-162 even\">\n\t<td class=\"column-1\">FR0013399474<\/td><td class=\"column-2\">GENKYOTEX<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-163 odd\">\n\t<td class=\"column-1\">FR0011799907<\/td><td class=\"column-2\">GENOMIC VISION<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-164 even\">\n\t<td class=\"column-1\">FR0004053510<\/td><td class=\"column-2\">GENOWAY<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-165 odd\">\n\t<td class=\"column-1\">FR0013183985<\/td><td class=\"column-2\">GENSIGHT BIOLOGICS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-166 even\">\n\t<td class=\"column-1\">FR0010533075<\/td><td class=\"column-2\">GETLINK SE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-167 odd\">\n\t<td class=\"column-1\">FR0000066672<\/td><td class=\"column-2\">GL EVENTS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-168 even\">\n\t<td class=\"column-1\">FR0011052257<\/td><td class=\"column-2\">GLOBAL BIOENERGIES<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-169 odd\">\n\t<td class=\"column-1\">FR0011289198<\/td><td class=\"column-2\">GLOBAL ECOPOWER<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-170 even\">\n\t<td class=\"column-1\">FR0013371507<\/td><td class=\"column-2\">GOUR MEDICAL<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-171 odd\">\n\t<td class=\"column-1\">FR0000065971<\/td><td class=\"column-2\">GRAINES VOLTZ<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-172 even\">\n\t<td class=\"column-1\">FR0011908045<\/td><td class=\"column-2\">GROUPE AG3I<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-173 odd\">\n\t<td class=\"column-1\">FR0014003RM7<\/td><td class=\"column-2\">GROUPE CASOL<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-174 even\">\n\t<td class=\"column-1\">FR0012384907<\/td><td class=\"column-2\">GROUPE CIOA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-175 odd\">\n\t<td class=\"column-1\">FR0000062671<\/td><td class=\"column-2\">GROUPE GORGE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-176 even\">\n\t<td class=\"column-1\">FR0012819381<\/td><td class=\"column-2\">GROUPE GUILLIN<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-177 odd\">\n\t<td class=\"column-1\">FR0000075442<\/td><td class=\"column-2\">GROUPE LDLC SA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-178 even\">\n\t<td class=\"column-1\">FR0004050300<\/td><td class=\"column-2\">GROUPE OPEN<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-179 odd\">\n\t<td class=\"column-1\">FR0013204070<\/td><td class=\"column-2\">GROUPE PAROT<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-180 even\">\n\t<td class=\"column-1\">FR0012612646<\/td><td class=\"column-2\">GROUPE PARTOUCHE REGROUPEES<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-181 odd\">\n\t<td class=\"column-1\">FR0004155000<\/td><td class=\"column-2\">GROUPE SFPI<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-182 even\">\n\t<td class=\"column-1\">FR0013429404<\/td><td class=\"column-2\">GROUPE TERA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-183 odd\">\n\t<td class=\"column-1\">FR0000032526<\/td><td class=\"column-2\">GUERBET<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-184 even\">\n\t<td class=\"column-1\">FR0000066755<\/td><td class=\"column-2\">HAULOTTE GROUP<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-185 odd\">\n\t<td class=\"column-1\">FR0013251584<\/td><td class=\"column-2\">HEALTH<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-186 even\">\n\t<td class=\"column-1\">FR0000066540<\/td><td class=\"column-2\">HERIGE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-187 odd\">\n\t<td class=\"column-1\">FR0004159473<\/td><td class=\"column-2\">HEXAOM<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-188 even\">\n\t<td class=\"column-1\">FR0000038531<\/td><td class=\"column-2\">HF COMPANY<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-189 odd\">\n\t<td class=\"column-1\">FR0000054231<\/td><td class=\"column-2\">HIGH CO<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-190 even\">\n\t<td class=\"column-1\">FR0000077562<\/td><td class=\"column-2\">HIOLLE INDUSTRIES<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-191 odd\">\n\t<td class=\"column-1\">FR0012821916<\/td><td class=\"column-2\">HIPAY GROUP<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-192 even\">\n\t<td class=\"column-1\">FR0010396309<\/td><td class=\"column-2\">HITECHPROS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-193 odd\">\n\t<td class=\"column-1\">FR0013451044<\/td><td class=\"column-2\">HOFFMANN GREEN CEMENT TECHNOLO<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-194 even\">\n\t<td class=\"column-1\">FR0012336691<\/td><td class=\"column-2\">HOME CONCEPT FRANCE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-195 odd\">\n\t<td class=\"column-1\">FR0014000U63<\/td><td class=\"column-2\">HOPIUM<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-196 even\">\n\t<td class=\"column-1\">FR0000065278<\/td><td class=\"column-2\">HOPSCOTCH GROUPE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-197 odd\">\n\t<td class=\"column-1\">FR0004153930<\/td><td class=\"column-2\">HYBRIGENICS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-198 even\">\n\t<td class=\"column-1\">FR0014003VY4<\/td><td class=\"column-2\">HYDROGENE FRCE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-199 odd\">\n\t<td class=\"column-1\">FR0014001PM5<\/td><td class=\"column-2\">HYDRO-REF-SOLUT<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-200 even\">\n\t<td class=\"column-1\">FR0011511971<\/td><td class=\"column-2\">I.CERAM<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-201 odd\">\n\t<td class=\"column-1\">FR0005854700<\/td><td class=\"column-2\">I2S<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-202 even\">\n\t<td class=\"column-1\">FR0000051393<\/td><td class=\"column-2\">IDI<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-203 odd\">\n\t<td class=\"column-1\">FR0000079691<\/td><td class=\"column-2\">IDS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-204 even\">\n\t<td class=\"column-1\">FR0000062184<\/td><td class=\"column-2\">IDSUD<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-205 odd\">\n\t<td class=\"column-1\">FR00140048X2<\/td><td class=\"column-2\">IKONISYS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-206 even\">\n\t<td class=\"column-1\">FR0013060100<\/td><td class=\"column-2\">IMMERSION<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-207 odd\">\n\t<td class=\"column-1\">FR0013470168<\/td><td class=\"column-2\">IMPLANET<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-208 even\">\n\t<td class=\"column-1\">FR0000066219<\/td><td class=\"column-2\">INDUSTRIELLE ET FINANC.D'ENT.<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-209 odd\">\n\t<td class=\"column-1\">FR0000071797<\/td><td class=\"column-2\">INFOTEL<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-210 even\">\n\t<td class=\"column-1\">FR0010331421<\/td><td class=\"column-2\">INNATE PHARMA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-211 odd\">\n\t<td class=\"column-1\">FR0010908723<\/td><td class=\"column-2\">INTEGRAGEN<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-212 even\">\n\t<td class=\"column-1\">FR0014003FN0<\/td><td class=\"column-2\">INTEGRIT VIAGER<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-213 odd\">\n\t<td class=\"column-1\">FR0011179886<\/td><td class=\"column-2\">INTRASENSE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-214 even\">\n\t<td class=\"column-1\">FR0013233012<\/td><td class=\"column-2\">INVENTIVA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-215 odd\">\n\t<td class=\"column-1\">BE0974299316<\/td><td class=\"column-2\">INVIBES ADVERTSING<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-216 even\">\n\t<td class=\"column-1\">FR0000072597<\/td><td class=\"column-2\">IT LINK<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-217 odd\">\n\t<td class=\"column-1\">FR0004026151<\/td><td class=\"column-2\">ITESOFT<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-218 even\">\n\t<td class=\"column-1\">FR0010082305<\/td><td class=\"column-2\">IVALIS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-219 odd\">\n\t<td class=\"column-1\">FR0012872141<\/td><td class=\"column-2\">JACQUES BOGART<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-220 even\">\n\t<td class=\"column-1\">FR0000033904<\/td><td class=\"column-2\">JACQUET METALS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-221 odd\">\n\t<td class=\"column-1\">FR0010722819<\/td><td class=\"column-2\">KALRAY<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-222 even\">\n\t<td class=\"column-1\">FR0004007813<\/td><td class=\"column-2\">KAUFMAN &amp; BROAD<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-223 odd\">\n\t<td class=\"column-1\">FR0013156007<\/td><td class=\"column-2\">KERLINK<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-224 even\">\n\t<td class=\"column-1\">FR0004029411<\/td><td class=\"column-2\">KEYRUS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-225 odd\">\n\t<td class=\"column-1\">BE0974274061<\/td><td class=\"column-2\">KINEPOLIS GROUP<\/td><td class=\"column-3\">Euronext Bruxelles<\/td>\n<\/tr>\n<tr class=\"row-226 even\">\n\t<td class=\"column-1\">FR0013374667<\/td><td class=\"column-2\">KKO INTERNATIONAL S.A.<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-227 odd\">\n\t<td class=\"column-1\">FR0011038348<\/td><td class=\"column-2\">KLARSEN SA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-228 even\">\n\t<td class=\"column-1\">FR0013419876<\/td><td class=\"column-2\">KUMULUS VAPE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-229 odd\">\n\t<td class=\"column-1\">FR0013030152<\/td><td class=\"column-2\">LA FRANCAISE DE L'ENERGIE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-230 even\">\n\t<td class=\"column-1\">FR0013155975<\/td><td class=\"column-2\">LA SAVONNERIE DE NYONS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-231 odd\">\n\t<td class=\"column-1\">FR0000066607<\/td><td class=\"column-2\">LACROIX GROUP SA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-232 even\">\n\t<td class=\"column-1\">FR0004027068<\/td><td class=\"column-2\">LANSON-BCC<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-233 odd\">\n\t<td class=\"column-1\">FR0013308582<\/td><td class=\"column-2\">LARGO<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-234 even\">\n\t<td class=\"column-1\">FR0000032278<\/td><td class=\"column-2\">LATECOERE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-235 odd\">\n\t<td class=\"column-1\">FR0006864484<\/td><td class=\"column-2\">LAURENT-PERRIER<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-236 even\">\n\t<td class=\"column-1\">FR0000075673<\/td><td class=\"column-2\">LE TANNEUR &amp; CIE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-237 odd\">\n\t<td class=\"column-1\">FR0000065484<\/td><td class=\"column-2\">LECTRA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-238 even\">\n\t<td class=\"column-1\">FR00140007I9<\/td><td class=\"column-2\">LES CONSTRUCTEURS DU BOIS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-239 odd\">\n\t<td class=\"column-1\">FR0007080254<\/td><td class=\"column-2\">LES HOTELS BAVEREZ<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-240 even\">\n\t<td class=\"column-1\">FR0011668821<\/td><td class=\"column-2\">LES TOQUES BLANCHES DU MONDE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-241 odd\">\n\t<td class=\"column-1\">FR0000033599<\/td><td class=\"column-2\">LEXIBOOK<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-242 even\">\n\t<td class=\"column-1\">FR0004156297<\/td><td class=\"column-2\">LINEDATA SERVICES<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-243 odd\">\n\t<td class=\"column-1\">ES0105089009<\/td><td class=\"column-2\">LLEIDANETWORKS SERVEIS TELEMAT<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-244 even\">\n\t<td class=\"column-1\">FR0004170017<\/td><td class=\"column-2\">LNA SANTE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-245 odd\">\n\t<td class=\"column-1\">FR0000044943<\/td><td class=\"column-2\">LOGIC INSTRUMENT<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-246 even\">\n\t<td class=\"column-1\">FR0011884378<\/td><td class=\"column-2\">LUCIBEL ACT.<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-247 odd\">\n\t<td class=\"column-1\">FR0000038242<\/td><td class=\"column-2\">LUMIBIRD<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-248 even\">\n\t<td class=\"column-1\">FR0013233475<\/td><td class=\"column-2\">LYSOGENE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-249 odd\">\n\t<td class=\"column-1\">FR0011770775<\/td><td class=\"column-2\">LYXOR PEA PME(DR)UCITS ETF FCP<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-250 even\">\n\t<td class=\"column-1\">FR0013270626<\/td><td class=\"column-2\">M2I<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-251 odd\">\n\t<td class=\"column-1\">FR0010328302<\/td><td class=\"column-2\">MADE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-252 even\">\n\t<td class=\"column-1\">FR0010812230<\/td><td class=\"column-2\">MADVERTISE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-253 odd\">\n\t<td class=\"column-1\">DE000A0HGQF5<\/td><td class=\"column-2\">MAGFORCE AG<\/td><td class=\"column-3\">Xetra<\/td>\n<\/tr>\n<tr class=\"row-254 even\">\n\t<td class=\"column-1\">FR0010827741<\/td><td class=\"column-2\">MAGILLEM DESIGN SERVICES<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-255 odd\">\n\t<td class=\"column-1\">FR0011092089<\/td><td class=\"column-2\">MAISON CLIO BLUE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-256 even\">\n\t<td class=\"column-1\">FR0000072993<\/td><td class=\"column-2\">MAKHEIA GROUP<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-257 odd\">\n\t<td class=\"column-1\">FR0000032302<\/td><td class=\"column-2\">MANUTAN INTERNATIONAL<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-258 even\">\n\t<td class=\"column-1\">FR0013400835<\/td><td class=\"column-2\">MARE NOSTRUM<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-259 odd\">\n\t<td class=\"column-1\">FR0000060873<\/td><td class=\"column-2\">MARIE BRIZARD WINE AND SPIRITS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-260 even\">\n\t<td class=\"column-1\">FR0004155687<\/td><td class=\"column-2\">MASTRAD<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-261 odd\">\n\t<td class=\"column-1\">FR0010609263<\/td><td class=\"column-2\">MAUNA KEA TECHNOLOGIES<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-262 even\">\n\t<td class=\"column-1\">FR0000051070<\/td><td class=\"column-2\">MAUREL ET PROM<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-263 odd\">\n\t<td class=\"column-1\">FR0011742329<\/td><td class=\"column-2\">MCPHY ENERGY<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-264 even\">\n\t<td class=\"column-1\">FR0010844464<\/td><td class=\"column-2\">MEDESIS PHARMA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-265 odd\">\n\t<td class=\"column-1\">FR0011049824<\/td><td class=\"column-2\">MEDIAN TECHNOLOGIES<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-266 even\">\n\t<td class=\"column-1\">FR0004065605<\/td><td class=\"column-2\">MEDINCELL<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-267 odd\">\n\t<td class=\"column-1\">FR0010298620<\/td><td class=\"column-2\">MEMSCAP (REGROUPE)<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-268 even\">\n\t<td class=\"column-1\">FR0004177046<\/td><td class=\"column-2\">METABOLIC EXPLORER<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-269 odd\">\n\t<td class=\"column-1\">FR0011217710<\/td><td class=\"column-2\">METHANOR<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-270 even\">\n\t<td class=\"column-1\">IT0004615396<\/td><td class=\"column-2\">METHORIOS CAPITAL<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-271 odd\">\n\t<td class=\"column-1\">FR0010353888<\/td><td class=\"column-2\">MGI DIGITAL GRAPHIC TECHNOLOGY<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-272 even\">\n\t<td class=\"column-1\">FR0000077570<\/td><td class=\"column-2\">MICROPOLE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-273 odd\">\n\t<td class=\"column-1\">FR0013053535<\/td><td class=\"column-2\">MILIBOO<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-274 even\">\n\t<td class=\"column-1\">FR0004172450<\/td><td class=\"column-2\">MINT SA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-275 odd\">\n\t<td class=\"column-1\">FR0011584549<\/td><td class=\"column-2\">MONTAGNE ET NEIGE DEVELOPPEMEN<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-276 even\">\n\t<td class=\"column-1\">FR0011033083<\/td><td class=\"column-2\">MOULINVEST<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-277 odd\">\n\t<td class=\"column-1\">FR0004034320<\/td><td class=\"column-2\">MR BRICOLAGE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-278 even\">\n\t<td class=\"column-1\">FR0012990968<\/td><td class=\"column-2\">MULANN<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-279 odd\">\n\t<td class=\"column-1\">FR0013230067<\/td><td class=\"column-2\">MULTIMICROCLOUD<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-280 even\">\n\t<td class=\"column-1\">FR0013462231<\/td><td class=\"column-2\">MUNIC<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-281 odd\">\n\t<td class=\"column-1\">FR0013482791<\/td><td class=\"column-2\">NACON<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-282 even\">\n\t<td class=\"column-1\">FR0014003J32<\/td><td class=\"column-2\">NAM.R<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-283 odd\">\n\t<td class=\"column-1\">FR0011341205<\/td><td class=\"column-2\">NANOBIOTIX<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-284 even\">\n\t<td class=\"column-1\">FR0013344223<\/td><td class=\"column-2\">NATURE ET LOGIS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-285 odd\">\n\t<td class=\"column-1\">FR0013018041<\/td><td class=\"column-2\">NAVYA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-286 even\">\n\t<td class=\"column-1\">FR0011636083<\/td><td class=\"column-2\">NEOLIFE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-287 odd\">\n\t<td class=\"column-1\">FR0004032746<\/td><td class=\"column-2\">NEOVACS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-288 even\">\n\t<td class=\"column-1\">FR0004154060<\/td><td class=\"column-2\">NETGEM<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-289 odd\">\n\t<td class=\"column-1\">FR0004171346<\/td><td class=\"column-2\">NEXTEDIA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-290 even\">\n\t<td class=\"column-1\">FR0014003XT0<\/td><td class=\"column-2\">NFL BIOSCIENCES<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-291 odd\">\n\t<td class=\"column-1\">FR0012650166<\/td><td class=\"column-2\">NHOA SA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-292 even\">\n\t<td class=\"column-1\">FR0010500363<\/td><td class=\"column-2\">NICOLAS MIGUET ET ASSOCIES REG<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-293 odd\">\n\t<td class=\"column-1\">FR0013018124<\/td><td class=\"column-2\">NICOX<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-294 even\">\n\t<td class=\"column-1\">FR0010397232<\/td><td class=\"column-2\">NOVACYT<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-295 odd\">\n\t<td class=\"column-1\">FR0000121691<\/td><td class=\"column-2\">NRJ GROUP<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-296 even\">\n\t<td class=\"column-1\">FR0000064529<\/td><td class=\"column-2\">NSC GROUPE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-297 odd\">\n\t<td class=\"column-1\">FR0004065639<\/td><td class=\"column-2\">NSE SA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-298 even\">\n\t<td class=\"column-1\">FR0013072741<\/td><td class=\"column-2\">O SORBET D'AMOUR<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-299 odd\">\n\t<td class=\"column-1\">FR0010231860<\/td><td class=\"column-2\">O2I<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-300 even\">\n\t<td class=\"column-1\">FR0010330613<\/td><td class=\"column-2\">OBER<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-301 odd\">\n\t<td class=\"column-1\">FR0014003711<\/td><td class=\"column-2\">OBIZ CONCEPT<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-302 even\">\n\t<td class=\"column-1\">FR0013310281<\/td><td class=\"column-2\">OCTOPUS BIOSAFETY<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-303 odd\">\n\t<td class=\"column-1\">FR0014003T71<\/td><td class=\"column-2\">OMER-DEC &amp; CIE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-304 even\">\n\t<td class=\"column-1\">FR0011766229<\/td><td class=\"column-2\">ONCODESIGN<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-305 odd\">\n\t<td class=\"column-1\">FR0013266772<\/td><td class=\"column-2\">ONE EXPERIENCE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-306 even\">\n\t<td class=\"column-1\">FR0010095596<\/td><td class=\"column-2\">ONXEO<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-307 odd\">\n\t<td class=\"column-1\">FR0000075392<\/td><td class=\"column-2\">ORAPI<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-308 even\">\n\t<td class=\"column-1\">FR0013318052<\/td><td class=\"column-2\">ORDISSIMO<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-309 odd\">\n\t<td class=\"column-1\">FR0010609206<\/td><td class=\"column-2\">OREGE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-310 even\">\n\t<td class=\"column-1\">FR0012127173<\/td><td class=\"column-2\">OSE IMMUNOTHERAPEUTICS SA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-311 odd\">\n\t<td class=\"column-1\">FR0013231180<\/td><td class=\"column-2\">OSMOZIS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-312 even\">\n\t<td class=\"column-1\">FR0013318813<\/td><td class=\"column-2\">PARAGON ID<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-313 odd\">\n\t<td class=\"column-1\">FR0000185928<\/td><td class=\"column-2\">PARFEX<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-314 even\">\n\t<td class=\"column-1\">FR0004038263<\/td><td class=\"column-2\">PARROT<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-315 odd\">\n\t<td class=\"column-1\">FR0013479730<\/td><td class=\"column-2\">PAULIC MEUNERIE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-316 even\">\n\t<td class=\"column-1\">FR0000053514<\/td><td class=\"column-2\">PCAS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-317 odd\">\n\t<td class=\"column-1\">FR0000061459<\/td><td class=\"column-2\">PERRIER (GERARD)<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-318 even\">\n\t<td class=\"column-1\">FR0012882389<\/td><td class=\"column-2\">PHARMAGEST INTERACTIVE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-319 odd\">\n\t<td class=\"column-1\">BE0974302342<\/td><td class=\"column-2\">PHARMASIMPLE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-320 even\">\n\t<td class=\"column-1\">FR0011191287<\/td><td class=\"column-2\">PHARNEXT<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-321 odd\">\n\t<td class=\"column-1\">FR0011651694<\/td><td class=\"column-2\">PHERECYDES PHARMA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-322 even\">\n\t<td class=\"column-1\">FR0000061608<\/td><td class=\"column-2\">PISCINES DESJOYAUX<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-323 odd\">\n\t<td class=\"column-1\">FR0011950641<\/td><td class=\"column-2\">PIXIUM VISION<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-324 even\">\n\t<td class=\"column-1\">FR0010211037<\/td><td class=\"column-2\">PLANET MEDIA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-325 odd\">\n\t<td class=\"column-1\">FR0010785790<\/td><td class=\"column-2\">PLANT ADVANCED TECHNOLOGIES<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-326 even\">\n\t<td class=\"column-1\">FR0013252186<\/td><td class=\"column-2\">PLASTIQUES DU VAL DE LOIRE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-327 odd\">\n\t<td class=\"column-1\">FR0000066441<\/td><td class=\"column-2\">POUJOULAT<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-328 even\">\n\t<td class=\"column-1\">FR0013015583<\/td><td class=\"column-2\">POULAILLON<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-329 odd\">\n\t<td class=\"column-1\">FR0012432516<\/td><td class=\"column-2\">POXEL<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-330 even\">\n\t<td class=\"column-1\">FR0014004EC4<\/td><td class=\"column-2\">PRECIA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-331 odd\">\n\t<td class=\"column-1\">FR0010169920<\/td><td class=\"column-2\">PREDILIFE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-332 even\">\n\t<td class=\"column-1\">FR0004044600<\/td><td class=\"column-2\">PRISMAFLEX INTERNATIONAL<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-333 odd\">\n\t<td class=\"column-1\">FR0010313486<\/td><td class=\"column-2\">PRODWARE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-334 even\">\n\t<td class=\"column-1\">FR0012613610<\/td><td class=\"column-2\">PRODWAYS GROUP<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-335 odd\">\n\t<td class=\"column-1\">FR0010380626<\/td><td class=\"column-2\">PROLOGUE (REGROUPE)<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-336 even\">\n\t<td class=\"column-1\">FR0011648971<\/td><td class=\"column-2\">QUANTUM GENOMICS REGROUPEES<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-337 odd\">\n\t<td class=\"column-1\">FR0010889386<\/td><td class=\"column-2\">QWAMPLIFY<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-338 even\">\n\t<td class=\"column-1\">FR0012395457<\/td><td class=\"column-2\">RAPIDO PRET<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-339 odd\">\n\t<td class=\"column-1\">FR0011858190<\/td><td class=\"column-2\">REALITES<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-340 even\">\n\t<td class=\"column-1\">FR0010820274<\/td><td class=\"column-2\">REWORLD MEDIA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-341 odd\">\n\t<td class=\"column-1\">FR0000075954<\/td><td class=\"column-2\">RIBER<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-342 even\">\n\t<td class=\"column-1\">FR0000039091<\/td><td class=\"column-2\">ROBERTET S.A.<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-343 odd\">\n\t<td class=\"column-1\">FR0000045601<\/td><td class=\"column-2\">ROBERTET S.A. (CI)<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-344 even\">\n\t<td class=\"column-1\">FR0013344173<\/td><td class=\"column-2\">ROCHE BOBOIS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-345 odd\">\n\t<td class=\"column-1\">FR0010523167<\/td><td class=\"column-2\">ROCTOOL<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-346 even\">\n\t<td class=\"column-1\">FR0000037640<\/td><td class=\"column-2\">ROUGIER<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-347 odd\">\n\t<td class=\"column-1\">FR0013467123<\/td><td class=\"column-2\">SAFE ORTHOPAEDICS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-348 even\">\n\t<td class=\"column-1\">FR0000060121<\/td><td class=\"column-2\">SAINT JEAN GROUPE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-349 odd\">\n\t<td class=\"column-1\">FR0004175222<\/td><td class=\"column-2\">SCIENTIFIC BRAIN TRAINING SBT<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-350 even\">\n\t<td class=\"column-1\">FR0000039109<\/td><td class=\"column-2\">SECHE ENVIRONNEMENT<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-351 odd\">\n\t<td class=\"column-1\">FR0012596468<\/td><td class=\"column-2\">SENSORION<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-352 even\">\n\t<td class=\"column-1\">FR0011950682<\/td><td class=\"column-2\">SERGEFERRARI GROUP<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-353 odd\">\n\t<td class=\"column-1\">FR0010282822<\/td><td class=\"column-2\">SES IMAGOTAG SA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-354 even\">\n\t<td class=\"column-1\">FR0010202606<\/td><td class=\"column-2\">SIDETRADE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-355 odd\">\n\t<td class=\"column-1\">FR0000060790<\/td><td class=\"column-2\">SIGNAUX GIROD<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-356 even\">\n\t<td class=\"column-1\">FR0000074122<\/td><td class=\"column-2\">SII<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-357 odd\">\n\t<td class=\"column-1\">FR0000065864<\/td><td class=\"column-2\">SOGECLAIR<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-358 even\">\n\t<td class=\"column-1\">FR0013227113<\/td><td class=\"column-2\">SOITEC<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-359 odd\">\n\t<td class=\"column-1\">FR00140006O9<\/td><td class=\"column-2\">SOLOCAL GROUP<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-360 even\">\n\t<td class=\"column-1\">FR0013379484<\/td><td class=\"column-2\">SOLUTIONS 30 SE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-361 odd\">\n\t<td class=\"column-1\">FR00140043Y1<\/td><td class=\"column-2\">SPARTOO<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-362 even\">\n\t<td class=\"column-1\">FR0011464452<\/td><td class=\"column-2\">SPINEGUARD<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-363 odd\">\n\t<td class=\"column-1\">FR0011398874<\/td><td class=\"column-2\">SPINEWAY<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-364 even\">\n\t<td class=\"column-1\">FR0011289040<\/td><td class=\"column-2\">SQLI RGPT<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-365 odd\">\n\t<td class=\"column-1\">FR0013006558<\/td><td class=\"column-2\">SRP GROUPE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-366 even\">\n\t<td class=\"column-1\">FR0000074775<\/td><td class=\"column-2\">STRADIM - ESPACE FINANCES SA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-367 odd\">\n\t<td class=\"column-1\">FR0010528059<\/td><td class=\"column-2\">STREAMWIDE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-368 even\">\n\t<td class=\"column-1\">FR0010526814<\/td><td class=\"column-2\">SUPERSONIC IMAGINE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-369 odd\">\n\t<td class=\"column-1\">FR0004180578<\/td><td class=\"column-2\">SWORD GROUP<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-370 even\">\n\t<td class=\"column-1\">FR0004529147<\/td><td class=\"column-2\">TESSI<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-371 odd\">\n\t<td class=\"column-1\">FR0013295789<\/td><td class=\"column-2\">TFF GROUP<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-372 even\">\n\t<td class=\"column-1\">FR0011053636<\/td><td class=\"column-2\">THE BLOCKCHAIN GROUP<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-373 odd\">\n\t<td class=\"column-1\">FR0010120402<\/td><td class=\"column-2\">THERACLION<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-374 even\">\n\t<td class=\"column-1\">FR0004197747<\/td><td class=\"column-2\">THERADIAG<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-375 odd\">\n\t<td class=\"column-1\">FR0013286259<\/td><td class=\"column-2\">THERANEXUS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-376 even\">\n\t<td class=\"column-1\">BE0974387194<\/td><td class=\"column-2\">THERAVET<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-377 odd\">\n\t<td class=\"column-1\">FR0013333432<\/td><td class=\"column-2\">THERMADOR GROUPE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-378 even\">\n\t<td class=\"column-1\">FR0000066482<\/td><td class=\"column-2\">TIPIAK<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-379 odd\">\n\t<td class=\"column-1\">FR0000060949<\/td><td class=\"column-2\">TIVOLY<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-380 even\">\n\t<td class=\"column-1\">FR0000033003<\/td><td class=\"column-2\">TOUAX<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-381 odd\">\n\t<td class=\"column-1\">FR0000035784<\/td><td class=\"column-2\">TRANSITION EVERGREEN<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-382 even\">\n\t<td class=\"column-1\">FR0005691656<\/td><td class=\"column-2\">TRIGANO<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-383 odd\">\n\t<td class=\"column-1\">FR0004175099<\/td><td class=\"column-2\">TRONICS MICROSYSTEMS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-384 even\">\n\t<td class=\"column-1\">FR0000079147<\/td><td class=\"column-2\">U10 CORP SA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-385 odd\">\n\t<td class=\"column-1\">FR0011070457<\/td><td class=\"column-2\">UCAR<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-386 even\">\n\t<td class=\"column-1\">FR0011776889<\/td><td class=\"column-2\">UMALIS GROUP<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-387 odd\">\n\t<td class=\"column-1\">FR0013263878<\/td><td class=\"column-2\">UMANIS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-388 even\">\n\t<td class=\"column-1\">FR0012709160<\/td><td class=\"column-2\">UNITI<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-389 odd\">\n\t<td class=\"column-1\">FR0010337865<\/td><td class=\"column-2\">UPERGY<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-390 even\">\n\t<td class=\"column-1\">FR0000074197<\/td><td class=\"column-2\">UTI GROUP<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-391 odd\">\n\t<td class=\"column-1\">FR0011898584<\/td><td class=\"column-2\">UV GERMI<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-392 even\">\n\t<td class=\"column-1\">FR0013254851<\/td><td class=\"column-2\">VALBIOTIS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-393 odd\">\n\t<td class=\"column-1\">FR0004056851<\/td><td class=\"column-2\">VALNEVA SE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-394 even\">\n\t<td class=\"column-1\">FR0012833770<\/td><td class=\"column-2\">VALONEO<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-395 odd\">\n\t<td class=\"column-1\">FR0010766667<\/td><td class=\"column-2\">VENTE-UNIQUE.COM<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-396 even\">\n\t<td class=\"column-1\">FR0010291245<\/td><td class=\"column-2\">VERIMATRIX<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-397 odd\">\n\t<td class=\"column-1\">FR0006174496<\/td><td class=\"column-2\">VERNEY CARON<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-398 even\">\n\t<td class=\"column-1\">FR0004186856<\/td><td class=\"column-2\">VETOQUINOL<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-399 odd\">\n\t<td class=\"column-1\">FR0010326090<\/td><td class=\"column-2\">VIALIFE SA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-400 even\">\n\t<td class=\"column-1\">FR0000031577<\/td><td class=\"column-2\">VIRBAC SA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-401 odd\">\n\t<td class=\"column-1\">FR0004029478<\/td><td class=\"column-2\">VISIATIV<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-402 even\">\n\t<td class=\"column-1\">FR0013481835<\/td><td class=\"column-2\">VISIOMED GROUP<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-403 odd\">\n\t<td class=\"column-1\">FR0011532225<\/td><td class=\"column-2\">VOGO<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-404 even\">\n\t<td class=\"column-1\">FR0004183960<\/td><td class=\"column-2\">VOLUNTIS<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-405 odd\">\n\t<td class=\"column-1\">FR0004045847<\/td><td class=\"column-2\">VOYAGEURS DU MONDE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-406 even\">\n\t<td class=\"column-1\">FR0000062796<\/td><td class=\"column-2\">VRANKEN-POMMERY MONOPOLE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-407 odd\">\n\t<td class=\"column-1\">FR0010131409<\/td><td class=\"column-2\">WALLIX GROUP<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-408 even\">\n\t<td class=\"column-1\">FR0013357621<\/td><td class=\"column-2\">WAVESTONE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-409 odd\">\n\t<td class=\"column-1\">FR0013079092<\/td><td class=\"column-2\">WE.CONNECT<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-410 even\">\n\t<td class=\"column-1\">FR0010688465<\/td><td class=\"column-2\">WEACCESS GROUP<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-411 odd\">\n\t<td class=\"column-1\">FR0010688440<\/td><td class=\"column-2\">WEDIA<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-412 even\">\n\t<td class=\"column-1\">FR0014000P11<\/td><td class=\"column-2\">WINFARM<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-413 odd\">\n\t<td class=\"column-1\">FR0013143872<\/td><td class=\"column-2\">WITBE<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-414 even\">\n\t<td class=\"column-1\">FR00140047H7<\/td><td class=\"column-2\">WIZIBOAT<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<tr class=\"row-415 odd\">\n\t<td class=\"column-1\">FR0004034072<\/td><td class=\"column-2\">XILAM ANIMATION<\/td><td class=\"column-3\">Euronext Paris<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n<\/div><!-- #tablepress-48 from cache -->\n<p>Pour rappel, <strong>c\u2019est au seul investisseur qu\u2019incombe la v\u00e9rification de l\u2019\u00e9ligibilit\u00e9 effective d\u2019une soci\u00e9t\u00e9 au PEA-PME.<\/strong><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Liste_des_fonds_eligibles_au_PEA-PME\"><\/span>Liste des fonds \u00e9ligibles au PEA-PME<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Les fonds \u00e9ligibles au PEA-PME sont des Sicav et fonds communs de placement (FCP) investis \u00e0 75% minimum en soci\u00e9t\u00e9s \u00e9ligibles.<\/p>\n<p>Aucune liste officielle des fonds PEA-PME n\u2019est \u00e9tablie par les pouvoirs publics. Pour \u00e9tablir la liste suivante, nous avons crois\u00e9 les donn\u00e9es de Boursorama, Morningstar et Quantalys.<\/p>\n<div id=\"tablepress-49-scroll-wrapper\" class=\"tablepress-scroll-wrapper\">\n\n<table id=\"tablepress-49\" class=\"tablepress tablepress-id-49 tablepress-responsive\">\n<thead>\n<tr class=\"row-1 odd\">\n\t<th class=\"column-1\">Nom du fonds<\/th><th class=\"column-2\">\u00c9toiles Morningstar<\/th><th class=\"column-3\">\u00c9toiles Quantalys<\/th>\n<\/tr>\n<\/thead>\n<tfoot>\n<tr class=\"row-62 even\">\n\t<th class=\"column-1\">Sources : Boursorama, Morningstar, Quantalys *Part ferm\u00e9e \u00e0 la souscription et au rachat <\/th><th class=\"column-2\"><\/th><th class=\"column-3\"><\/th>\n<\/tr>\n<\/tfoot>\n<tbody class=\"row-hover\">\n<tr class=\"row-2 even\">\n\t<td class=\"column-1\">29 Haussmann Multi-Managers PEA-PME<\/td><td class=\"column-2\">Non not\u00e9<\/td><td class=\"column-3\">Non not\u00e9<\/td>\n<\/tr>\n<tr class=\"row-3 odd\">\n\t<td class=\"column-1\">ACA PME PEA<\/td><td class=\"column-2\">3<\/td><td class=\"column-3\">Non not\u00e9<\/td>\n<\/tr>\n<tr class=\"row-4 even\">\n\t<td class=\"column-1\">Advanced Small Caps Euro RD<\/td><td class=\"column-2\">4<\/td><td class=\"column-3\">4<\/td>\n<\/tr>\n<tr class=\"row-5 odd\">\n\t<td class=\"column-1\">AIM Lux C-Quadrat Europe Microcap R EUR<\/td><td class=\"column-2\">Non not\u00e9<\/td><td class=\"column-3\">Non not\u00e9<\/td>\n<\/tr>\n<tr class=\"row-6 even\">\n\t<td class=\"column-1\">Allianz Actions Euro PME-ETI RC<\/td><td class=\"column-2\">4<\/td><td class=\"column-3\">4<\/td>\n<\/tr>\n<tr class=\"row-7 odd\">\n\t<td class=\"column-1\">ALM S\u00e9lection PEA-PME RB<\/td><td class=\"column-2\">Non not\u00e9<\/td><td class=\"column-3\">Non not\u00e9<\/td>\n<\/tr>\n<tr class=\"row-8 even\">\n\t<td class=\"column-1\">Amundi Actions PME C<\/td><td class=\"column-2\">4<\/td><td class=\"column-3\">3<\/td>\n<\/tr>\n<tr class=\"row-9 odd\">\n\t<td class=\"column-1\">Amundi Multi-G\u00e9rants PEA PME<\/td><td class=\"column-2\">5<\/td><td class=\"column-3\">4<\/td>\n<\/tr>\n<tr class=\"row-10 even\">\n\t<td class=\"column-1\">BNP Paribas Actions PME ETI ISR R<\/td><td class=\"column-2\">3<\/td><td class=\"column-3\">1<\/td>\n<\/tr>\n<tr class=\"row-11 odd\">\n\t<td class=\"column-1\">BNP Paribas Actions PME ISR I<\/td><td class=\"column-2\">2<\/td><td class=\"column-3\">1<\/td>\n<\/tr>\n<tr class=\"row-12 even\">\n\t<td class=\"column-1\">BSO PME<\/td><td class=\"column-2\">3<\/td><td class=\"column-3\">2<\/td>\n<\/tr>\n<tr class=\"row-13 odd\">\n\t<td class=\"column-1\">Chaussier PME Croissance<\/td><td class=\"column-2\">2<\/td><td class=\"column-3\">1<\/td>\n<\/tr>\n<tr class=\"row-14 even\">\n\t<td class=\"column-1\">Claresco PME P<\/td><td class=\"column-2\">4<\/td><td class=\"column-3\">1<\/td>\n<\/tr>\n<tr class=\"row-15 odd\">\n\t<td class=\"column-1\">DNCA Actions Euro PME R<\/td><td class=\"column-2\">4<\/td><td class=\"column-3\">1<\/td>\n<\/tr>\n<tr class=\"row-16 even\">\n\t<td class=\"column-1\">Echiquier Entrepreneurs A<\/td><td class=\"column-2\">4<\/td><td class=\"column-3\">5<\/td>\n<\/tr>\n<tr class=\"row-17 odd\">\n\t<td class=\"column-1\">Echiquier Excelsior A<\/td><td class=\"column-2\">3<\/td><td class=\"column-3\">2<\/td>\n<\/tr>\n<tr class=\"row-18 even\">\n\t<td class=\"column-1\">Erasmus Small Cap Euro R<\/td><td class=\"column-2\">5<\/td><td class=\"column-3\">4<\/td>\n<\/tr>\n<tr class=\"row-19 odd\">\n\t<td class=\"column-1\">ERES Multigestion PME A<\/td><td class=\"column-2\">Non not\u00e9<\/td><td class=\"column-3\">Non not\u00e9<\/td>\n<\/tr>\n<tr class=\"row-20 even\">\n\t<td class=\"column-1\">Etoile PME C<\/td><td class=\"column-2\">4<\/td><td class=\"column-3\">3<\/td>\n<\/tr>\n<tr class=\"row-21 odd\">\n\t<td class=\"column-1\">Federal Transition Territoires P<\/td><td class=\"column-2\">3<\/td><td class=\"column-3\">1<\/td>\n<\/tr>\n<tr class=\"row-22 even\">\n\t<td class=\"column-1\">Friedland PME P<\/td><td class=\"column-2\">4<\/td><td class=\"column-3\">4<\/td>\n<\/tr>\n<tr class=\"row-23 odd\">\n\t<td class=\"column-1\">G Fund Avenir Small Cap NC<\/td><td class=\"column-2\">3<\/td><td class=\"column-3\">4<\/td>\n<\/tr>\n<tr class=\"row-24 even\">\n\t<td class=\"column-1\">Gay-Lussac Microcaps A*<\/td><td class=\"column-2\">5<\/td><td class=\"column-3\">5<\/td>\n<\/tr>\n<tr class=\"row-25 odd\">\n\t<td class=\"column-1\">Gay-Lussac Microcaps H<\/td><td class=\"column-2\">Non not\u00e9<\/td><td class=\"column-3\">5<\/td>\n<\/tr>\n<tr class=\"row-26 even\">\n\t<td class=\"column-1\">Gestys Sant\u00e9 Biotech<\/td><td class=\"column-2\">1<\/td><td class=\"column-3\">1<\/td>\n<\/tr>\n<tr class=\"row-27 odd\">\n\t<td class=\"column-1\">Gresham S\u00e9lection PME AC<\/td><td class=\"column-2\">3<\/td><td class=\"column-3\">2<\/td>\n<\/tr>\n<tr class=\"row-28 even\">\n\t<td class=\"column-1\">Gresham Strat\u00e9gie Midcaps AC<\/td><td class=\"column-2\">3<\/td><td class=\"column-3\">5<\/td>\n<\/tr>\n<tr class=\"row-29 odd\">\n\t<td class=\"column-1\">HMG D\u00e9couvertes PME C<\/td><td class=\"column-2\">Non not\u00e9<\/td><td class=\"column-3\"><\/td>\n<\/tr>\n<tr class=\"row-30 even\">\n\t<td class=\"column-1\">HSBC Euro PME AC<\/td><td class=\"column-2\">3<\/td><td class=\"column-3\">2<\/td>\n<\/tr>\n<tr class=\"row-31 odd\">\n\t<td class=\"column-1\">IDAM Small Euro A<\/td><td class=\"column-2\">3<\/td><td class=\"column-3\">3<\/td>\n<\/tr>\n<tr class=\"row-32 even\">\n\t<td class=\"column-1\">Ind\u00e9pendance et Expansion Europe Small AC<\/td><td class=\"column-2\">1<\/td><td class=\"column-3\">3<\/td>\n<\/tr>\n<tr class=\"row-33 odd\">\n\t<td class=\"column-1\">Lazard Investissement Microcaps*<\/td><td class=\"column-2\">2<\/td><td class=\"column-3\">1<\/td>\n<\/tr>\n<tr class=\"row-34 even\">\n\t<td class=\"column-1\">Lazard Investissement PEA-PME A<\/td><td class=\"column-2\">3<\/td><td class=\"column-3\">1<\/td>\n<\/tr>\n<tr class=\"row-35 odd\">\n\t<td class=\"column-1\">LCL D\u00e9veloppement PME C<\/td><td class=\"column-2\">4<\/td><td class=\"column-3\">3<\/td>\n<\/tr>\n<tr class=\"row-36 even\">\n\t<td class=\"column-1\">Lonvia Avenir Small Cap Europe R<\/td><td class=\"column-2\">Non not\u00e9<\/td><td class=\"column-3\">Non not\u00e9<\/td>\n<\/tr>\n<tr class=\"row-37 odd\">\n\t<td class=\"column-1\">MAM France PME<\/td><td class=\"column-2\">3<\/td><td class=\"column-3\">4<\/td>\n<\/tr>\n<tr class=\"row-38 even\">\n\t<td class=\"column-1\">Mandarine Europe Microcap I EUR<\/td><td class=\"column-2\">4<\/td><td class=\"column-3\">5<\/td>\n<\/tr>\n<tr class=\"row-39 odd\">\n\t<td class=\"column-1\">MCA Entreprendre PME<\/td><td class=\"column-2\">4<\/td><td class=\"column-3\">5<\/td>\n<\/tr>\n<tr class=\"row-40 even\">\n\t<td class=\"column-1\">Montbleu Sherpa C<\/td><td class=\"column-2\">1<\/td><td class=\"column-3\">1<\/td>\n<\/tr>\n<tr class=\"row-41 odd\">\n\t<td class=\"column-1\">Nova Europe ISR A<\/td><td class=\"column-2\">4<\/td><td class=\"column-3\">3<\/td>\n<\/tr>\n<tr class=\"row-42 even\">\n\t<td class=\"column-1\">Oddo BHF Active Micro Cap CR-EUR<\/td><td class=\"column-2\">4<\/td><td class=\"column-3\">4<\/td>\n<\/tr>\n<tr class=\"row-43 odd\">\n\t<td class=\"column-1\">Oddo Cap Horizons PME ETI CI-EUR<\/td><td class=\"column-2\">5<\/td><td class=\"column-3\">5<\/td>\n<\/tr>\n<tr class=\"row-44 even\">\n\t<td class=\"column-1\">Ofi Actions PME-ETI C<\/td><td class=\"column-2\">4<\/td><td class=\"column-3\">Non analys\u00e9<\/td>\n<\/tr>\n<tr class=\"row-45 odd\">\n\t<td class=\"column-1\">Portzamparc Europe PME ISR C<\/td><td class=\"column-2\">3<\/td><td class=\"column-3\">2<\/td>\n<\/tr>\n<tr class=\"row-46 even\">\n\t<td class=\"column-1\">Portzamparc PME ISR C<\/td><td class=\"column-2\">3<\/td><td class=\"column-3\">2<\/td>\n<\/tr>\n<tr class=\"row-47 odd\">\n\t<td class=\"column-1\">Promepar PME Opportunit\u00e9s O<\/td><td class=\"column-2\">4<\/td><td class=\"column-3\">4<\/td>\n<\/tr>\n<tr class=\"row-48 even\">\n\t<td class=\"column-1\">Quadrige France SmallCaps C<\/td><td class=\"column-2\">2<\/td><td class=\"column-3\">1<\/td>\n<\/tr>\n<tr class=\"row-49 odd\">\n\t<td class=\"column-1\">Roche-Brune Euro PME P<\/td><td class=\"column-2\">3<\/td><td class=\"column-3\">2<\/td>\n<\/tr>\n<tr class=\"row-50 even\">\n\t<td class=\"column-1\">Sextant PME A<\/td><td class=\"column-2\">4<\/td><td class=\"column-3\">3<\/td>\n<\/tr>\n<tr class=\"row-51 odd\">\n\t<td class=\"column-1\">SG Actions Euro PME C<\/td><td class=\"column-2\">4<\/td><td class=\"column-3\">3<\/td>\n<\/tr>\n<tr class=\"row-52 even\">\n\t<td class=\"column-1\">Sunny Managers F<\/td><td class=\"column-2\">4<\/td><td class=\"column-3\">3<\/td>\n<\/tr>\n<tr class=\"row-53 odd\">\n\t<td class=\"column-1\">Tailor Actions Entrepreneurs C<\/td><td class=\"column-2\">Non not\u00e9<\/td><td class=\"column-3\">Non not\u00e9<\/td>\n<\/tr>\n<tr class=\"row-54 even\">\n\t<td class=\"column-1\">Talence Selection PME AC<\/td><td class=\"column-2\">3<\/td><td class=\"column-3\">2<\/td>\n<\/tr>\n<tr class=\"row-55 odd\">\n\t<td class=\"column-1\">Tiepolo PME C<\/td><td class=\"column-2\">5<\/td><td class=\"column-3\">1<\/td>\n<\/tr>\n<tr class=\"row-56 even\">\n\t<td class=\"column-1\">Tocqueville PME D<\/td><td class=\"column-2\">3<\/td><td class=\"column-3\">1<\/td>\n<\/tr>\n<tr class=\"row-57 odd\">\n\t<td class=\"column-1\">Tremplin PME M<\/td><td class=\"column-2\">4<\/td><td class=\"column-3\">5<\/td>\n<\/tr>\n<tr class=\"row-58 even\">\n\t<td class=\"column-1\">Trusteam ROC PME<\/td><td class=\"column-2\">3<\/td><td class=\"column-3\">2<\/td>\n<\/tr>\n<tr class=\"row-59 odd\">\n\t<td class=\"column-1\">UFF Hexagone PME<\/td><td class=\"column-2\">2<\/td><td class=\"column-3\">3<\/td>\n<\/tr>\n<tr class=\"row-60 even\">\n\t<td class=\"column-1\">UFF Tremplin PME C<\/td><td class=\"column-2\">3<\/td><td class=\"column-3\">4<\/td>\n<\/tr>\n<tr class=\"row-61 odd\">\n\t<td class=\"column-1\">Uz\u00e8s Boscary S\u00e9lection<\/td><td class=\"column-2\">3<\/td><td class=\"column-3\">4<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n<\/div><!-- #tablepress-49 from cache -->\n<h2><span class=\"ez-toc-section\" id=\"Tracker_PEA-PME_ETF_Lyxor_PEA_PME_PEAP\"><\/span>Tracker PEA-PME\u00a0: ETF Lyxor PEA PME (PEAP)<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Un seul ETF ou tracker \u00e9ligible au PEA-PME existe sur le march\u00e9\u00a0: il s\u2019agit de l\u2019ETF Lyxor PEA PME (PEAP &#8211; FR0011770775), qui r\u00e9plique les performances de l\u2019indice CAC PME, cr\u00e9\u00e9 en f\u00e9vrier 2014 pour servir de support \u00e0 la cr\u00e9ation de trackers d\u00e9di\u00e9s au PEA PME.<\/p>\n<p>Ce tracker fait partie des plus mal not\u00e9s de la cat\u00e9gorie Actions Europe, avec 1 \u00e9toile Morningstar et Quantalys sur 5 possibles.<\/p>\n<p>L\u2019indice CAC PME suit les performances de 40 entreprises fran\u00e7aises \u00e9ligibles au PEA PME, cot\u00e9es en Bourse \u00e0 Paris sur Euronext (march\u00e9 r\u00e9glement\u00e9) et Euronext Growth.<\/p>\n<p>Le poids de chaque constituant de l\u2019indice est plafonn\u00e9 \u00e0 7,5%. Pour \u00e9viter tout biais sectoriel trop important, les secteurs sont cap\u00e9s \u00e0 25% de l\u2019indice.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"PEA-PME_Assurance_quelques_contrats_a_frais_reduits\"><\/span>PEA-PME Assurance\u00a0: quelques contrats \u00e0 frais r\u00e9duits<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Le PEA-PME Assurance est une alternative au PEA-PME bancaire beaucoup moins courante. Cette possibilit\u00e9 d\u2019ouvrir un PEA-PME aupr\u00e8s d\u2019une compagnie d\u2019assurance vie est pr\u00e9vue par la loi \u00e0 aux articles L221-32-1 et L221-32-2 du Code mon\u00e9taire et financier.<\/p>\n<p>Le PEA-PME prend alors la forme d\u2019un contrat de capitalisation investi en part de fonds \u00e9ligibles au PEA-PME.<\/p>\n<p>Il existe \u00e0 notre connaissance quatre PEA-PME Assurance sur le march\u00e9, tous assur\u00e9s par Suravenir (compagnie du Cr\u00e9dit Mutuel Arkea).<\/p>\n<p>Trois sont directement accessibles en ligne :<\/p>\n<ul>\n<li>Linxea Avenir PEA PME : 15 fonds propos\u00e9s en gestion libre<\/li>\n<li>meilleurtaux PEA PME Capi : 15 fonds propos\u00e9s en gestion libre, gestion profil\u00e9e sans frais additionnels<\/li>\n<li>Puissance Avenir PEA PME : 13 fonds propos\u00e9s<\/li>\n<\/ul>\n<p>Ces contrats sont quasiment des clones et offrent un choix de supports quasiment identique. La tarification est la m\u00eame :<\/p>\n<ul>\n<li>0 frais sur versements<\/li>\n<li>0 frais d\u2019arbitrage<\/li>\n<li>0% de frais de gestion dans le cadre fiscal du PEA-PME<\/li>\n<\/ul>\n<p>Ces contrats sont int\u00e9ressants pour les \u00e9pargnants souhaitant confier l\u2019int\u00e9gralit\u00e9 de la gestion de leur portefeuille \u00e0 des g\u00e9rants sp\u00e9cialis\u00e9s.<\/p>\n<p>L\u2019investissement en titre vifs (choix de titres de soci\u00e9t\u00e9 cot\u00e9es) n\u2019est pas accessible via ces contrats.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Historique_du_PEA-PME\"><\/span>Historique du PEA-PME<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h3>La gen\u00e8se du PEA-PME<\/h3>\n<p>L\u2019id\u00e9e de cr\u00e9er un PEA affect\u00e9 uniquement aux PME a germ\u00e9 en 2011 dans l\u2019esprit de responsables de plusieurs think-tank promoteurs du financement des PME (PME Finance), de l\u2019investissement en actions (l\u2019Institut Pro-Actions \u2013 IPA) et de dirigeants de la place financi\u00e8re de Paris, comme Robert de Vog\u00fce, PDG d\u2019Arkeon Finance.<\/p>\n<p>L\u2019action de PME Finance et de l\u2019Institut Pro-Actions a conduit l\u2019ancien d\u00e9put\u00e9 des Yvelines Jean-Michel Fourgous, alors pr\u00e9sident du groupe d\u2019\u00e9tudes sur les PME \u00e0 l\u2019Assembl\u00e9e nationale, \u00e0 d\u00e9poser en octobre 2011 un amendement au projet de loi de finances 2012, qui a \u00e9t\u00e9 rejet\u00e9.<\/p>\n<p>Le concept a refait surface en septembre 2012 lors d\u2019une allocation de Fran\u00e7ois Hollande et s\u2019est mat\u00e9rialis\u00e9 le 29 avril 2013 \u00e0 l\u2019occasion de la cl\u00f4ture des Assises de l\u2019entrepreneuriat \u00e0 l\u2019Elys\u00e9e. Durant cet \u00e9v\u00e9nement, le gouvernement a pr\u00e9sent\u00e9 les grandes lignes du PEA-PME.<\/p>\n<p>Les caract\u00e9ristiques d\u00e9finitives du PEA-PME ont \u00e9t\u00e9 d\u00e9finies dans la loi de finances pour 2014. L\u2019essentiel du dispositif avait \u00e9t\u00e9 pr\u00e9sent\u00e9 pr\u00e9alablement, le 26 ao\u00fbt 2013 par l\u2019ancien ministre de l\u2019Economie Pierre Moscovici.<\/p>\n<h3>Le PEA-PME en quelques dates cl\u00e9s<\/h3>\n<ul>\n<li>22 f\u00e9vrier 2011 : Arkeon Finance propose la cr\u00e9ation d\u2019un PEA \u00ab Soci\u00e9t\u00e9s petites et moyennes \u00bb<\/li>\n<li>6 octobre 2011 : colloque \u00e0 l\u2019Assembl\u00e9e Nationale o\u00f9 PME Finance et IPA sugg\u00e8rent aux d\u00e9put\u00e9s de cr\u00e9er le PEA-PME<\/li>\n<li>12 octobre 2011 : d\u00e9p\u00f4t et rejet de l\u2019amendement Fourgous proposant un PEA-PME plafonn\u00e9 \u00e0 118.000 euros<\/li>\n<li>20 septembre 2012 : annonce par Fran\u00e7ois Hollande d\u2019un PEA-PME dans le cadre de la remise du prix de l\u2019Audace cr\u00e9atrice<\/li>\n<li>5 novembre 2012 : remise du rapport Gallois sur la comp\u00e9titivit\u00e9, qui recommande la cr\u00e9ation d\u2019un avantage fiscal \u00ab pour d\u00e9boucher sur un v\u00e9ritable PEA-PME \u00bb<\/li>\n<li>2 avril 2013 : remise du rapport Berger-Lefebvre sur l\u2019\u00e9pargne longue pr\u00f4nant la cr\u00e9ation d\u2019un PEA-PME<\/li>\n<li>29 avril 2013 : pr\u00e9sentation des grandes lignes du PEA-PME lors de la cl\u00f4ture des Assises de l\u2019entrepreneuriat \u00e0 l\u2019Elys\u00e9e<\/li>\n<li>26 ao\u00fbt 2013 : pr\u00e9sentation de la r\u00e9forme du PEA et de la cr\u00e9ation du PEA-PME par Pierre Moscovici en Bretagne<\/li>\n<li>25 septembre 2013 : pr\u00e9sentation du projet de loi de finances pour 2014 contenant l\u2019article 53 sur le PEA-PME<\/li>\n<li>14 novembre 2013 : vote de l\u2019article 53 du projet de Budget 2014 par l\u2019Assembl\u00e9e nationale<\/li>\n<li>20 d\u00e9cembre 2013 : vote d\u00e9finitif au Parlement<\/li>\n<li>30 d\u00e9cembre 2013 : publication au JORF de la loi de finances initiale, article 70 consacr\u00e9 au PEA-PME1er janvier 2014 : entr\u00e9e en vigueur de la loi<\/li>\n<li>5 mars 2014 : publication du d\u00e9cret d\u2019application au JO<\/li>\n<li>6 mars 2014 : ouverture des souscriptions<\/li>\n<li>1er janvier 2016 : nouveaux crit\u00e8res d\u2019\u00e9ligibilit\u00e9 pour les soci\u00e9t\u00e9 et ouverture au titres obligataires<\/li>\n<li>24 mai 2019 : entr\u00e9e en vigueur de la loi Pacte (nouveau plafond)<\/li>\n<li>1er juillet 2020 : entr\u00e9e en vigueur du plafonnement des frais des PEA et PEA-PME<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"PEA-PME_avis_de_la_redaction\"><\/span>PEA-PME : avis de la r\u00e9daction<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Le PEA-PME est un excellent outil d\u2019un point de vue patrimonial, gr\u00e2ce \u00e0 son r\u00e9gime fiscal d\u00e9rogatoire, identique \u00e0 celui du PEA. B\u00e9n\u00e9ficier d\u2019une exon\u00e9ration totale d\u2019imp\u00f4t sur le revenu sur les gains au bout de 5 ans est un luxe, que seuls le <a href=\"https:\/\/www.toutsurmesfinances.com\/placements\/pee-definition-abondement-deblocage-et-fiscalite-du-plan-d-epargne-entreprise.html\">plan d&rsquo;\u00e9pargne entreprise (PEE)<\/a> et le PEA classique offrent. Via le PEA-PME, l\u2019investisseur individuel peut investir directement et\/ou indirectement dans des PME cot\u00e9es et non cot\u00e9es, dans un cadre fiscal plus cl\u00e9ment que le compte-titres ou le compte d\u2019instruments financiers (CIF).<\/p>\n<p>Cependant, le choix de titres et fonds \u00e9ligibles, par d\u00e9finition restreint, limite forc\u00e9ment l\u2019int\u00e9r\u00eat du PEA PME. Le fait d\u2019\u00eatre concentr\u00e9 sur les PME-ETI fran\u00e7aises n\u2019offre pas les m\u00eames possibilit\u00e9s que le PEA et encore moins du <a href=\"https:\/\/www.toutsurmesfinances.com\/bourse\/a\/le-compte-titre\">compte-titres ordinaire (CTO)<\/a>. Toutefois, le PEA-PME est ind\u00e9niablement compl\u00e9mentaire aux deux enveloppes pr\u00e9c\u00e9dentes\u00a0: le PEA-PME peut parfaitement servir \u00e0 loger des titres et fonds investis en PME-ETI fran\u00e7aises, et les autres enveloppes \u00e0 tous les autres supports accessibles, que ce dans le cadre d\u2019une gestion diversifi\u00e9e ou de conviction sur un nombre limit\u00e9 de titres.<\/p>\n<p>Enfin, la possibilit\u00e9 &#8211; r\u00e9cente &#8211; d\u2019investir dans le financement participatif avec l\u2019avantage fiscal du PEA est un atout ind\u00e9niable pour les \u00e9pargnants qui s\u2019adonnent au crowdlending, via des plateformes de pr\u00eat.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le PEA-PME permet principalement d&rsquo;investir dans des actions de petites et moyennes valeurs cot\u00e9es et non cot\u00e9es dans la limite de 225.000 euros, avec les avantages de la fiscalit\u00e9 du PEA classique. Tour d&rsquo;horizon du dispositif et des titres \u00e9ligibles<\/p>\n","protected":false},"author":13709,"featured_media":47811,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[125],"tags":[],"class_list":["post-35955","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comment-investir"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PEA-PME ETI : conditions, liste de titres \u00e9ligibles, fiscalit\u00e9, avis<\/title>\n<meta name=\"description\" content=\"Le PEA-PME permet d&#039;investir en actions de petites et moyennes valeurs cot\u00e9es en Bourse et non cot\u00e9es dans la limite de 225.000 \u20ac, avec la fiscalit\u00e9 du PEA\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.toutsurmesfinances.com\/bourse\/a\/pea-pme-conditions-fonctionnement-et-fiscalite-du-pea-dedie-aux-pme-eti\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PEA-PME ETI : conditions, liste de titres \u00e9ligibles, fiscalit\u00e9, avis\" \/>\n<meta property=\"og:description\" content=\"Le PEA-PME permet d&#039;investir en actions de petites et moyennes valeurs cot\u00e9es en Bourse et non cot\u00e9es dans la limite de 225.000 \u20ac, avec la fiscalit\u00e9 du PEA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.toutsurmesfinances.com\/bourse\/a\/pea-pme-conditions-fonctionnement-et-fiscalite-du-pea-dedie-aux-pme-eti\" \/>\n<meta property=\"og:site_name\" content=\"Bourse\" \/>\n<meta property=\"article:published_time\" content=\"2013-07-22T15:13:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-23T18:26:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.toutsurmesfinances.com\/bourse\/wp-content\/uploads\/sites\/10\/2013\/07\/pea-pme-fonctionnement.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Olivier Brunet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TSMF_Bourse\" \/>\n<meta name=\"twitter:site\" content=\"@TSMF_Bourse\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Olivier Brunet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.toutsurmesfinances.com\/bourse\/a\/pea-pme-conditions-fonctionnement-et-fiscalite-du-pea-dedie-aux-pme-eti#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.toutsurmesfinances.com\/bourse\/a\/pea-pme-conditions-fonctionnement-et-fiscalite-du-pea-dedie-aux-pme-eti\"},\"author\":{\"name\":\"Olivier Brunet\",\"@id\":\"https:\/\/www.toutsurmesfinances.com\/bourse\/#\/schema\/person\/f3692b3163890cd1408bd0dc68a1b55a\"},\"headline\":\"PEA-PME : conditions, fonctionnement et fiscalit\u00e9 du PEA d\u00e9di\u00e9 aux PME-ETI\",\"dateModified\":\"2021-07-23T18:26:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.toutsurmesfinances.com\/bourse\/a\/pea-pme-conditions-fonctionnement-et-fiscalite-du-pea-dedie-aux-pme-eti\"},\"wordCount\":2792,\"publisher\":{\"@id\":\"https:\/\/www.toutsurmesfinances.com\/bourse\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.toutsurmesfinances.com\/bourse\/a\/pea-pme-conditions-fonctionnement-et-fiscalite-du-pea-dedie-aux-pme-eti#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.toutsurmesfinances.com\/bourse\/wp-content\/uploads\/sites\/10\/2013\/07\/pea-pme-fonctionnement.jpg\",\"articleSection\":[\"Comment investir\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.toutsurmesfinances.com\/bourse\/a\/pea-pme-conditions-fonctionnement-et-fiscalite-du-pea-dedie-aux-pme-eti\",\"url\":\"https:\/\/www.toutsurmesfinances.com\/bourse\/a\/pea-pme-conditions-fonctionnement-et-fiscalite-du-pea-dedie-aux-pme-eti\",\"name\":\"PEA-PME ETI : conditions, liste de titres \u00e9ligibles, fiscalit\u00e9, avis\",\"isPartOf\":{\"@id\":\"https:\/\/www.toutsurmesfinances.com\/bourse\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.toutsurmesfinances.com\/bourse\/a\/pea-pme-conditions-fonctionnement-et-fiscalite-du-pea-dedie-aux-pme-eti#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.toutsurmesfinances.com\/bourse\/a\/pea-pme-conditions-fonctionnement-et-fiscalite-du-pea-dedie-aux-pme-eti#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.toutsurmesfinances.com\/bourse\/wp-content\/uploads\/sites\/10\/2013\/07\/pea-pme-fonctionnement.jpg\",\"dateModified\":\"2021-07-23T18:26:54+00:00\",\"description\":\"Le PEA-PME permet d'investir en actions de petites et moyennes valeurs cot\u00e9es en Bourse et non cot\u00e9es dans la limite de 225.000 \u20ac, avec la fiscalit\u00e9 du PEA\",\"breadcrumb\":{\"@id\":\"https:\/\/www.toutsurmesfinances.com\/bourse\/a\/pea-pme-conditions-fonctionnement-et-fiscalite-du-pea-dedie-aux-pme-eti#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.toutsurmesfinances.com\/bourse\/a\/pea-pme-conditions-fonctionnement-et-fiscalite-du-pea-dedie-aux-pme-eti\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.toutsurmesfinances.com\/bourse\/a\/pea-pme-conditions-fonctionnement-et-fiscalite-du-pea-dedie-aux-pme-eti#primaryimage\",\"url\":\"https:\/\/www.toutsurmesfinances.com\/bourse\/wp-content\/uploads\/sites\/10\/2013\/07\/pea-pme-fonctionnement.jpg\",\"contentUrl\":\"https:\/\/www.toutsurmesfinances.com\/bourse\/wp-content\/uploads\/sites\/10\/2013\/07\/pea-pme-fonctionnement.jpg\",\"width\":480,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.toutsurmesfinances.com\/bourse\/a\/pea-pme-conditions-fonctionnement-et-fiscalite-du-pea-dedie-aux-pme-eti#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.toutsurmesfinances.com\/bourse\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PEA-PME : conditions, fonctionnement et fiscalit\u00e9 du PEA d\u00e9di\u00e9 aux PME-ETI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.toutsurmesfinances.com\/bourse\/#website\",\"url\":\"https:\/\/www.toutsurmesfinances.com\/bourse\/\",\"name\":\"Bourse\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.toutsurmesfinances.com\/bourse\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.toutsurmesfinances.com\/bourse\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.toutsurmesfinances.com\/bourse\/#organization\",\"name\":\"Tout Sur Mes Finances\",\"url\":\"https:\/\/www.toutsurmesfinances.com\/bourse\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.toutsurmesfinances.com\/bourse\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.toutsurmesfinances.com\/bourse\/wp-content\/uploads\/sites\/10\/2021\/01\/favicon.png\",\"contentUrl\":\"https:\/\/www.toutsurmesfinances.com\/bourse\/wp-content\/uploads\/sites\/10\/2021\/01\/favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Tout Sur Mes Finances\"},\"image\":{\"@id\":\"https:\/\/www.toutsurmesfinances.com\/bourse\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/TSMF_Bourse\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.toutsurmesfinances.com\/bourse\/#\/schema\/person\/f3692b3163890cd1408bd0dc68a1b55a\",\"name\":\"Olivier Brunet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.toutsurmesfinances.com\/bourse\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/59a19214b7bb3163a27d873fa61f9a80?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/59a19214b7bb3163a27d873fa61f9a80?s=96&d=mm&r=g\",\"caption\":\"Olivier Brunet\"},\"description\":\"Olivier Brunet est cofondateur de\u00a0ToutSurMesFinances.com\u00a0et r\u00e9dacteur en chef sp\u00e9cialis\u00e9 en placements et fiscalit\u00e9\u00a0des particuliers. Pr\u00e9sent\u00a0au sein du\u00a0m\u00e9dia\u00a0depuis sa cr\u00e9ation, il en est l\u2019un des piliers \u00e9ditoriaux. Il analyse les strat\u00e9gies d\u2019investissement,\u00a0suit\u00a0les \u00e9volutions fiscales et les\u00a0probl\u00e9matiques\u00a0patrimoniales\u00a0avec une vision long terme, forg\u00e9e par des ann\u00e9es de pratique et de suivi des march\u00e9s.\u00a0\",\"sameAs\":[\"https:\/\/www.toutsurmesfinances.com\/author\/olivier\",\"https:\/\/www.linkedin.com\/in\/obrunet\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PEA-PME ETI : conditions, liste de titres \u00e9ligibles, fiscalit\u00e9, avis","description":"Le PEA-PME permet d'investir en actions de petites et moyennes valeurs cot\u00e9es en Bourse et non cot\u00e9es dans la limite de 225.000 \u20ac, avec la fiscalit\u00e9 du PEA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.toutsurmesfinances.com\/bourse\/a\/pea-pme-conditions-fonctionnement-et-fiscalite-du-pea-dedie-aux-pme-eti","og_locale":"fr_FR","og_type":"article","og_title":"PEA-PME ETI : conditions, liste de titres \u00e9ligibles, fiscalit\u00e9, avis","og_description":"Le PEA-PME permet d'investir en actions de petites et moyennes valeurs cot\u00e9es en Bourse et non cot\u00e9es dans la limite de 225.000 \u20ac, avec la fiscalit\u00e9 du PEA","og_url":"https:\/\/www.toutsurmesfinances.com\/bourse\/a\/pea-pme-conditions-fonctionnement-et-fiscalite-du-pea-dedie-aux-pme-eti","og_site_name":"Bourse","article_published_time":"2013-07-22T15:13:14+00:00","article_modified_time":"2021-07-23T18:26:54+00:00","og_image":[{"width":480,"height":360,"url":"https:\/\/www.toutsurmesfinances.com\/bourse\/wp-content\/uploads\/sites\/10\/2013\/07\/pea-pme-fonctionnement.jpg","type":"image\/jpeg"}],"author":"Olivier Brunet","twitter_card":"summary_large_image","twitter_creator":"@TSMF_Bourse","twitter_site":"@TSMF_Bourse","twitter_misc":{"\u00c9crit par":"Olivier Brunet","Dur\u00e9e de lecture estim\u00e9e":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.toutsurmesfinances.com\/bourse\/a\/pea-pme-conditions-fonctionnement-et-fiscalite-du-pea-dedie-aux-pme-eti#article","isPartOf":{"@id":"https:\/\/www.toutsurmesfinances.com\/bourse\/a\/pea-pme-conditions-fonctionnement-et-fiscalite-du-pea-dedie-aux-pme-eti"},"author":{"name":"Olivier Brunet","@id":"https:\/\/www.toutsurmesfinances.com\/bourse\/#\/schema\/person\/f3692b3163890cd1408bd0dc68a1b55a"},"headline":"PEA-PME : conditions, fonctionnement et fiscalit\u00e9 du PEA d\u00e9di\u00e9 aux PME-ETI","dateModified":"2021-07-23T18:26:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.toutsurmesfinances.com\/bourse\/a\/pea-pme-conditions-fonctionnement-et-fiscalite-du-pea-dedie-aux-pme-eti"},"wordCount":2792,"publisher":{"@id":"https:\/\/www.toutsurmesfinances.com\/bourse\/#organization"},"image":{"@id":"https:\/\/www.toutsurmesfinances.com\/bourse\/a\/pea-pme-conditions-fonctionnement-et-fiscalite-du-pea-dedie-aux-pme-eti#primaryimage"},"thumbnailUrl":"https:\/\/www.toutsurmesfinances.com\/bourse\/wp-content\/uploads\/sites\/10\/2013\/07\/pea-pme-fonctionnement.jpg","articleSection":["Comment investir"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.toutsurmesfinances.com\/bourse\/a\/pea-pme-conditions-fonctionnement-et-fiscalite-du-pea-dedie-aux-pme-eti","url":"https:\/\/www.toutsurmesfinances.com\/bourse\/a\/pea-pme-conditions-fonctionnement-et-fiscalite-du-pea-dedie-aux-pme-eti","name":"PEA-PME ETI : conditions, liste de titres \u00e9ligibles, fiscalit\u00e9, avis","isPartOf":{"@id":"https:\/\/www.toutsurmesfinances.com\/bourse\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.toutsurmesfinances.com\/bourse\/a\/pea-pme-conditions-fonctionnement-et-fiscalite-du-pea-dedie-aux-pme-eti#primaryimage"},"image":{"@id":"https:\/\/www.toutsurmesfinances.com\/bourse\/a\/pea-pme-conditions-fonctionnement-et-fiscalite-du-pea-dedie-aux-pme-eti#primaryimage"},"thumbnailUrl":"https:\/\/www.toutsurmesfinances.com\/bourse\/wp-content\/uploads\/sites\/10\/2013\/07\/pea-pme-fonctionnement.jpg","dateModified":"2021-07-23T18:26:54+00:00","description":"Le PEA-PME permet d'investir en actions de petites et moyennes valeurs cot\u00e9es en Bourse et non cot\u00e9es dans la limite de 225.000 \u20ac, avec la fiscalit\u00e9 du PEA","breadcrumb":{"@id":"https:\/\/www.toutsurmesfinances.com\/bourse\/a\/pea-pme-conditions-fonctionnement-et-fiscalite-du-pea-dedie-aux-pme-eti#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.toutsurmesfinances.com\/bourse\/a\/pea-pme-conditions-fonctionnement-et-fiscalite-du-pea-dedie-aux-pme-eti"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.toutsurmesfinances.com\/bourse\/a\/pea-pme-conditions-fonctionnement-et-fiscalite-du-pea-dedie-aux-pme-eti#primaryimage","url":"https:\/\/www.toutsurmesfinances.com\/bourse\/wp-content\/uploads\/sites\/10\/2013\/07\/pea-pme-fonctionnement.jpg","contentUrl":"https:\/\/www.toutsurmesfinances.com\/bourse\/wp-content\/uploads\/sites\/10\/2013\/07\/pea-pme-fonctionnement.jpg","width":480,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/www.toutsurmesfinances.com\/bourse\/a\/pea-pme-conditions-fonctionnement-et-fiscalite-du-pea-dedie-aux-pme-eti#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.toutsurmesfinances.com\/bourse\/"},{"@type":"ListItem","position":2,"name":"PEA-PME : conditions, fonctionnement et fiscalit\u00e9 du PEA d\u00e9di\u00e9 aux PME-ETI"}]},{"@type":"WebSite","@id":"https:\/\/www.toutsurmesfinances.com\/bourse\/#website","url":"https:\/\/www.toutsurmesfinances.com\/bourse\/","name":"Bourse","description":"","publisher":{"@id":"https:\/\/www.toutsurmesfinances.com\/bourse\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.toutsurmesfinances.com\/bourse\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.toutsurmesfinances.com\/bourse\/#organization","name":"Tout Sur Mes Finances","url":"https:\/\/www.toutsurmesfinances.com\/bourse\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.toutsurmesfinances.com\/bourse\/#\/schema\/logo\/image\/","url":"https:\/\/www.toutsurmesfinances.com\/bourse\/wp-content\/uploads\/sites\/10\/2021\/01\/favicon.png","contentUrl":"https:\/\/www.toutsurmesfinances.com\/bourse\/wp-content\/uploads\/sites\/10\/2021\/01\/favicon.png","width":512,"height":512,"caption":"Tout Sur Mes Finances"},"image":{"@id":"https:\/\/www.toutsurmesfinances.com\/bourse\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/TSMF_Bourse"]},{"@type":"Person","@id":"https:\/\/www.toutsurmesfinances.com\/bourse\/#\/schema\/person\/f3692b3163890cd1408bd0dc68a1b55a","name":"Olivier Brunet","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.toutsurmesfinances.com\/bourse\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/59a19214b7bb3163a27d873fa61f9a80?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/59a19214b7bb3163a27d873fa61f9a80?s=96&d=mm&r=g","caption":"Olivier Brunet"},"description":"Olivier Brunet est cofondateur de\u00a0ToutSurMesFinances.com\u00a0et r\u00e9dacteur en chef sp\u00e9cialis\u00e9 en placements et fiscalit\u00e9\u00a0des particuliers. Pr\u00e9sent\u00a0au sein du\u00a0m\u00e9dia\u00a0depuis sa cr\u00e9ation, il en est l\u2019un des piliers \u00e9ditoriaux. Il analyse les strat\u00e9gies d\u2019investissement,\u00a0suit\u00a0les \u00e9volutions fiscales et les\u00a0probl\u00e9matiques\u00a0patrimoniales\u00a0avec une vision long terme, forg\u00e9e par des ann\u00e9es de pratique et de suivi des march\u00e9s.\u00a0","sameAs":["https:\/\/www.toutsurmesfinances.com\/author\/olivier","https:\/\/www.linkedin.com\/in\/obrunet\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.toutsurmesfinances.com\/bourse\/wp-json\/wp\/v2\/posts\/35955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.toutsurmesfinances.com\/bourse\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.toutsurmesfinances.com\/bourse\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.toutsurmesfinances.com\/bourse\/wp-json\/wp\/v2\/users\/13709"}],"replies":[{"embeddable":true,"href":"https:\/\/www.toutsurmesfinances.com\/bourse\/wp-json\/wp\/v2\/comments?post=35955"}],"version-history":[{"count":4,"href":"https:\/\/www.toutsurmesfinances.com\/bourse\/wp-json\/wp\/v2\/posts\/35955\/revisions"}],"predecessor-version":[{"id":48316,"href":"https:\/\/www.toutsurmesfinances.com\/bourse\/wp-json\/wp\/v2\/posts\/35955\/revisions\/48316"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.toutsurmesfinances.com\/bourse\/wp-json\/wp\/v2\/media\/47811"}],"wp:attachment":[{"href":"https:\/\/www.toutsurmesfinances.com\/bourse\/wp-json\/wp\/v2\/media?parent=35955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.toutsurmesfinances.com\/bourse\/wp-json\/wp\/v2\/categories?post=35955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.toutsurmesfinances.com\/bourse\/wp-json\/wp\/v2\/tags?post=35955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}